{"id":492,"date":"2017-07-06T16:03:45","date_gmt":"2017-07-06T14:03:45","guid":{"rendered":"http:\/\/www.picweb.it\/emm\/blog\/?p=492"},"modified":"2017-07-09T13:14:59","modified_gmt":"2017-07-09T11:14:59","slug":"rispetto-per-il-ponte-di-tiberio-a-rimini","status":"publish","type":"post","link":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/07\/06\/rispetto-per-il-ponte-di-tiberio-a-rimini\/","title":{"rendered":"Rispetto per il Ponte di Tiberio a Rimini"},"content":{"rendered":"<p>\u00c8 di questi giorni la notizia dell\u2019avanzare del cantiere per la realizzazione del progetto che modificher\u00e0, in maniera drammatica, la vista del Ponte di Tiberio e delle mura lungo il corso del Marecchia a Rimini!<\/p>\n<p>Pi\u00f9 che il mero discorso estetico, ci\u00f2 che lascia basiti \u00e8 la presa di posizione, in difesa dello scempio, di chi dovrebbe prevenire e tutelare i nostri monumenti e il nostro ambiente.<\/p>\n<p>Il progetto consiste nella realizzazione di una \u201c<em>passerella leggera a sbalzo<\/em>\u201d lungo l\u2019argine di destra del Marecchia, a valle del Ponte di Tiberio, nonch\u00e9 nella installazione di una \u201c<em>piazza ed un<\/em> <em>ponte galleggianti<\/em>\u201d sul corso d\u2019cqua. Il tutto, a detta dell\u2019assessore ai lavori pubblici Jamil Sadegholvaad, riguarderebbe un progetto di \u201c<em>riqualificazione del Ponte di Tiberio e dell\u2019intera area<\/em>\u201d.<\/p>\n<figure id=\"attachment_493\" aria-describedby=\"caption-attachment-493\" style=\"width: 1141px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"493\" data-permalink=\"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/07\/06\/rispetto-per-il-ponte-di-tiberio-a-rimini\/comparto_4_-_z5_nmod\/\" data-orig-file=\"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/comparto_4_-_z5_nmod.jpg\" data-orig-size=\"800,500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"comparto_4_-_z5_nmod\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Rendering del progetto in corso&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/comparto_4_-_z5_nmod.jpg\" class=\" wp-image-493\" src=\"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/comparto_4_-_z5_nmod.jpg\" alt=\"\" width=\"1141\" height=\"713\" srcset=\"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/comparto_4_-_z5_nmod.jpg 800w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/comparto_4_-_z5_nmod-300x188.jpg 300w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/comparto_4_-_z5_nmod-768x480.jpg 768w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/comparto_4_-_z5_nmod-700x438.jpg 700w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/comparto_4_-_z5_nmod-520x325.jpg 520w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/comparto_4_-_z5_nmod-360x225.jpg 360w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/comparto_4_-_z5_nmod-250x156.jpg 250w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/comparto_4_-_z5_nmod-100x63.jpg 100w\" sizes=\"(max-width: 1141px) 100vw, 1141px\" \/><figcaption id=\"caption-attachment-493\" class=\"wp-caption-text\">Rendering del progetto in corso<\/figcaption><\/figure>\n<figure id=\"attachment_494\" aria-describedby=\"caption-attachment-494\" style=\"width: 1139px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" data-attachment-id=\"494\" data-permalink=\"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/07\/06\/rispetto-per-il-ponte-di-tiberio-a-rimini\/comparto-4-z6-amod-640x360\/\" data-orig-file=\"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/Comparto-4-Z6-Amod-640x360.jpg\" data-orig-size=\"640,360\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Comparto-4-Z6-Amod-640&amp;#215;360\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Rendering del progetto in corso&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/Comparto-4-Z6-Amod-640x360.jpg\" class=\" wp-image-494\" src=\"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/Comparto-4-Z6-Amod-640x360.jpg\" alt=\"\" width=\"1139\" height=\"641\" srcset=\"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/Comparto-4-Z6-Amod-640x360.jpg 640w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/Comparto-4-Z6-Amod-640x360-300x169.jpg 300w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/Comparto-4-Z6-Amod-640x360-520x293.jpg 520w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/Comparto-4-Z6-Amod-640x360-360x203.jpg 360w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/Comparto-4-Z6-Amod-640x360-250x141.jpg 250w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/Comparto-4-Z6-Amod-640x360-100x56.jpg 100w\" sizes=\"(max-width: 1139px) 100vw, 1139px\" \/><figcaption id=\"caption-attachment-494\" class=\"wp-caption-text\">Rendering del progetto in corso<\/figcaption><\/figure>\n<p>Ebbene, andando punto per punto, potremmo iniziare col ritenere alquanto discutibile definire \u201c<em>leggera<\/em>\u201d una struttura del genere.<\/p>\n<p>Per realizzare la passerella infatti, \u00e8 gi\u00e0 stata messa in atto l\u2019apertura di una serie di fori quadrati, di circa 60 cm di lato e con un interasse inferiore al metro di distanza, all\u2019interno delle mura malatestiane dell\u2019argine destro. Le aperture sono state realizzate mediante il taglio delle strutture con macchine taglia-muro che, ovviamente, se mai fosse vero ci\u00f2 che si legge, ovvero che \u201c<em>il materiale della cortina tagliata \u00e8 stato recuperato per essere ricollocato una volta inserite le mensole a sbalzo\u201d<\/em>, il paramento murario, in corrispondenza dei \u201c<em>rattoppi<\/em>\u201d risulter\u00e0 privo della regolare indentatura tra i vari ricorsi, a causa del taglio verticale non preceduto da un\u2019operazione di \u201c<em>scucitura<\/em>\u201d della cortina muraria, che avrebbe consentito la perfetta ricollocazione \u201c<em>invisibile<\/em>\u201d degli elementi rimossi.<\/p>\n<p>In ogni modo, ritenere \u201c<em>leggera<\/em>\u201d una struttura del genere, solo perch\u00e9 realizzata con travi e parapetti metallici e pedana in legno ha del paradossale. I promotori di certe iniziative infatti, amano nascondersi dietro un abuso terminologico per manipolare l\u2019opinione pubblica. Essi sanno infatti bene che, specie qui in Italia, basta usare termini come \u201c<em>sostenibile<\/em>\u201d, \u201c<em>leggero<\/em>\u201d, \u201c<em>invisibile<\/em>\u201d, \u201c<em>temporaneo<\/em>\u201d, \u201c<em>amovibile<\/em>\u201d, ecc. perch\u00e9 la gente gli creda! \u2026 Tuttavia sappiamo bene che non ci sia nulla di pi\u00f9 permanente di ci\u00f2 che venga installato come temporaneo.<\/p>\n<p>Dalla Tour Eiffel ai chioschi e \u201c<em>verande<\/em>\u201d dei bar e ristoranti lungo le strade delle citt\u00e0, passando per le \u201c<em>case temporanee<\/em>\u201d realizzate all\u2019indomani di terremoti e mai rimosse, il mondo \u00e8 pieno di opere \u201c<em>temporanee e amovibili<\/em>\u201d! In questo caso, se mai si possa ritenere \u201c<em>leggero<\/em>\u201d il tipo di materiali proposti \u2013 affermazione falsissima \u2013 che cosa dovremmo dire del \u201c<em>pesantissimo<\/em>\u201d impatto visivo che ne scaturirebbe? Forse sarebbe il caso di smetterla di prendere in giro la gente, ubriacandola di falsit\u00e0 pronunciate dai presunti \u201c<em>esperti<\/em>\u201d privi di senso etico (oltre che estetico)!<\/p>\n<p>Se si vuol parlare di riqualificazione, o di valorizzazione del Ponte di Tiberio, probabilmente occorrerebbe parlare della sua trasformazione definitiva in ponte pedonale, piuttosto che promuovere un intervento che, deviando il traffico ciclo-pedonale sul ridicolo \u201c<em>ponte galleggiante<\/em>\u201d, lo condannerebbe a restare un ponte carrabile!<\/p>\n<p>A tal proposito, inoltre, occorrerebbe riflettere sulla mobilit\u00e0 proposta<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>. Stiamo parlando di un percorso che, dagli elaborati visibili, risulta limitarsi alla passerella ed al ponte, che non presenta ramificazioni all\u2019interno del tessuto cittadino a destra e sinistra del Marecchia \u2026 un po\u2019 come il Ponte di Messina che si vorrebbe realizzare in assenza di autostrade e ferrovie dignitose in Calabria e Sicilia, oppure ancora come certi progetti di nuove \u201cpiazze\u201d promossi da chi non sappia che una piazza, per poter funzionare, debba essere parte integrante di un sistema di percorsi pedonali che invitino la gente a muoversi usando le proprie gambe.<\/p>\n<p>Una delle cose pi\u00f9 comiche di questo progetto risulta poi il modo in cui sia stato concepito per i ciclisti; ma ve l\u2019immaginate \u2013 in una citt\u00e0 dove i ciclisti sfrecciano che sembrano gareggiare per il Giro d\u2019Italia \u2013 come potrebbe mai funzionare l\u2019obbligo dell\u2019attraversamento in \u201c<em>bici a mano<\/em>\u201d di questo percorso? \u2026 A certi progettisti mi vien da fare la stessa domanda che Enrico Lucci de \u201c<em>Le Iene<\/em>\u201d pose a Vittorio Gregotti, progettista dello ZEN di Palermo: \u201c<em>ma non \u00e8 che spesso gli architetti c\u2019hanno in testa una cosa che a loro gli sembra bella, poi realizzano una cosa e l\u00e0 dentro ci dovranno vivere migliaia di persone, che vivranno la loro vita in un posto schifoso?<\/em>\u201d<\/p>\n<p>La realt\u00e0 del nostro Paese \u00e8 che, indipendentemente dalla reale funzionalit\u00e0 ed utilit\u00e0 di certe realizzazioni, quando c\u2019\u00e8 il rischio di perdere un possibile finanziamento, si d\u00e0 il via a progettazioni e realizzazioni utili solo ed esclusivamente allo sperpero di denaro pubblico! Manca una visione d\u2019insieme, perch\u00e9 mancano i tempi politici per mettere in atto progetti a medio lungo termine, che possano davvero risolvere le problematiche delle citt\u00e0. Chi governa deve, per ragioni politiche, dimostrare di aver fatto qualcosa nel suo breve mandato, ergo non \u00e8 immaginabile la promozione di un progetto la cui realizzazione possa eccedere i 3 o 4 anni \u2026 anche perch\u00e9 l\u2019amministrazione che seguir\u00e0, molto probabilmente, l\u2019abbandoner\u00e0!<\/p>\n<p>Rimini ha dei problemi molto pi\u00f9 importanti da affrontare, che non questa ridicola installazione deturpante. Si pensi alla difficolt\u00e0 di collegamento tra la citt\u00e0 vecchia e il mare, a causa della cesura rappresentata dalla ferrovia, nonch\u00e9 dalla recente, inutile e costosissima realizzazione del TRC. Si pensi, sempre in tema, alla ai sottopassaggi pedonali che, all\u2019imbrunire, fanno paura! Il problema della \u201c<em>ricucitura<\/em>\u201d del tessuto urbano tra Centro Storico e fronte mare \u00e8 senz\u2019altro un problema che oltre a creare posti di lavoro, porterebbe grandissimi benefici alla citt\u00e0 in termini di sicurezza e mobilit\u00e0!<\/p>\n<p>Che dire della necessit\u00e0 di liberare e rivalutare l\u2019area dell\u2019anfiteatro? Che dire del problema dello spostamento del mercato e della liberazione delle piazze storiche? Insomma, se si volessero davvero spendere denari pubblici, di ragioni valide ce ne sarebbero moltissime.<\/p>\n<p>Un\u2019ultima annotazione va fatta in merito alle dichiarazioni del responsabile della Soprintendenza a giustificazione delle aperture nelle mura lungo il Marecchia<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a>. Alle proteste e ai legittimi dubbi di chi chiedesse come fosse possibile consentire uno scempio del genere nelle mura lungo il Marecchia, l\u2019arch. Napoli della Soprintendenza ha infatti replicato che \u201c<em>quelle mura non sono medievali-malatestiane ma restaurate di recente, mentre quelle che verranno abbattute sono dei semplici tamponamenti altrettanto recenti<\/em>\u201d (sic!).<\/p>\n<p>Ebbene, al responsabile della Soprintendenza vorrei ricordare che il problema non pu\u00f2 essere limitato alla paternit\u00e0 e\/o datazione di un manufatto, bens\u00ec <strong>alla tutela dell\u2019integrit\u00e0 di un contesto urbano di notevole pregio<\/strong>!<\/p>\n<p>L\u2019attuale normativa infatti, e nello specifico il DL 22 gennaio 2004, n\u00b042, relativamente ai <strong>beni paesaggistici sottoposti a tutela<\/strong>, ricorda che <strong>per \u201c<em>paesaggio<\/em>\u201d si intende una parte omogenea di territorio i cui caratteri derivano dalla natura, dalla storia umana o dalle reciproche interrelazioni<\/strong>.<\/p>\n<p>Ai sensi dell\u2019<strong>articolo 134 <\/strong>del nuovo codice, si considerano beni paesaggistici e quindi sottoposti a tutela:<\/p>\n<ol>\n<li><strong>gli immobili e le aree di notevole interesse pubblico<\/strong> indicati nel successivo articolo 136;<\/li>\n<li>l<strong>e aree tutelate per legge per il loro interesse paesaggistico<\/strong> ed indicate nel successivo articolo 142;<\/li>\n<li><strong>gli immobili e le aree comunque sottoposti a tutela dai singoli piani paesaggistici<\/strong>.<\/li>\n<\/ol>\n<p>Ai fini dell\u2019individuazione dei beni paesaggistici sottoposti a tutela, si rammenta che, per l\u2019articolo 136, si considerano immobili ed aree di notevole interesse pubblico:<\/p>\n<ol>\n<li><strong>le cose immobili che hanno cospicui caratteri di bellezza naturale o di singolarit\u00e0 geologica<\/strong>;<\/li>\n<li>le ville, i giardini e i parchi, non tutelati dalle disposizioni della Parte seconda del presente codice, che si distinguono per la loro non comune bellezza;<\/li>\n<li><strong>i complessi di cose immobili che compongono un caratteristico aspetto avente valore estetico e tradizionale;<\/strong><\/li>\n<li><strong>le bellezze panoramiche considerate come quadri e cos\u00ec pure quei punti di vista o di belvedere, accessibili al pubblico, dai quali si goda lo spettacolo di quelle bellezze<\/strong>.<\/li>\n<\/ol>\n<p>Invece, per aree tutelate direttamente per legge, ai sensi dell\u2019articolo 142, si intendono:<\/p>\n<ol>\n<li>i territori costieri compresi in una fascia della profondit\u00e0 di 300 metri dalla linea di battigia, anche per i terreni elevati sul mare;<\/li>\n<li>i territori contermini ai laghi compresi in una fascia della profondit\u00e0 di 300 metri dalla linea di battigia, anche per i territori elevati sui laghi;<\/li>\n<li><strong>i fiumi, i torrenti, i corsi d\u2019acqua iscritti negli elenchi previsti dal testo unico delle disposizioni di legge sulle acque<\/strong> ed impianti elettrici, approvato con regio decreto n. 1775\/1933, <strong>e le relative sponde o piedi degli argini per una fascia di 150 metri ciascuna<\/strong>;<\/li>\n<li>le montagne per la parte <strong>eccedente<\/strong>600 metri sul livello del mare per la catena alpina e 1.200 metri sul livello del mare per la catena appenninica e per le isole;<\/li>\n<li>i ghiacciai e i circhi glaciali;<\/li>\n<li>i parchi e le riserve nazionali o regionali e i territori di protezione esterna dei parchi;<\/li>\n<li>i territori coperti da foreste e da boschi, ancorch\u00e9 percorsi o danneggiati dal fuoco, e quelli sottoposti a vincolo di rimboschimento, come definiti dall\u2019articolo 2, commi 2 e 6, del decreto legislativo n. 227\/2001;<\/li>\n<li>le aree assegnate alle universit\u00e0 agrarie e le zone gravate da usi civici;<\/li>\n<li>le zone umide incluse nell\u2019elenco previsto dal D.P.R. n. 448\/1976;<\/li>\n<li>i vulcani;<\/li>\n<li><strong>le zone di interesse archeologico individuate alla data del 1\u00b0 maggio 2004<\/strong>.<\/li>\n<\/ol>\n<p>A questo punto non posso che augurarmi che queste parole possano essere prese in considerazione da parte di chi rivesta degli incarichi pubblici al fine di tutelare le nostre citt\u00e0, piuttosto che consentire inutili capricci che non faranno che mortificarle!<\/p>\n<p>I tanti recenti errori urbanistico-architettonici, generati dall\u2019arroganza e dalla presunzione di politici ed architetti, si spera, dovrebbero aver insegnato qualcosa.<\/p>\n<p>Rimini \u00e8 ancora in tempo per tornare indietro, evitando inutili scempi come quello messo in atto alla Spezia ad opera di Buren, a causa dell\u2019ottuso atteggiamento dispotico del sindaco e della soprintendenza locali, sordi alle preghiere della stragrande maggioranza degli spezzini che implorava di bloccare lo scempio di Piazza Verdi.<\/p>\n<figure id=\"attachment_495\" aria-describedby=\"caption-attachment-495\" style=\"width: 1340px\" class=\"wp-caption alignnone\"><img decoding=\"async\" data-attachment-id=\"495\" data-permalink=\"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/07\/06\/rispetto-per-il-ponte-di-tiberio-a-rimini\/20170612_112603\/\" data-orig-file=\"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/20170612_112603.jpg\" data-orig-size=\"4128,2322\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"20170612_112603\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Vista dell\u2019immonda sistemazione di Piazza Verdi alla Spezia&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/20170612_112603-1024x576.jpg\" class=\" wp-image-495\" src=\"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/20170612_112603.jpg\" alt=\"\" width=\"1340\" height=\"754\" srcset=\"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/20170612_112603.jpg 4128w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/20170612_112603-300x169.jpg 300w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/20170612_112603-768x432.jpg 768w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/20170612_112603-1024x576.jpg 1024w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/20170612_112603-700x394.jpg 700w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/20170612_112603-520x293.jpg 520w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/20170612_112603-360x203.jpg 360w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/20170612_112603-250x141.jpg 250w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/20170612_112603-100x56.jpg 100w\" sizes=\"(max-width: 1340px) 100vw, 1340px\" \/><figcaption id=\"caption-attachment-495\" class=\"wp-caption-text\">Vista dell\u2019immonda sistemazione di Piazza Verdi alla Spezia<\/figcaption><\/figure>\n<p>Un politico sano di mente dovrebbe ambire al massimo consenso pubblico, piuttosto che a rendersi inviso alla cittadinanza.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> <a href=\"http:\/\/www.newsrimini.it\/2017\/06\/progetto-tiberio-modifiche-alla-viabilita-interventi-conclusi-per-fine-anno\/\">http:\/\/www.newsrimini.it\/2017\/06\/progetto-tiberio-modifiche-alla-viabilita-interventi-conclusi-per-fine-anno\/<\/a><\/p>\n<p><a href=\"http:\/\/www.newsrimini.it\/2017\/07\/passerella-al-ponte-tiberio-le-precisazione-dei-progettisti\/\">http:\/\/www.newsrimini.it\/2017\/07\/passerella-al-ponte-tiberio-le-precisazione-dei-progettisti\/<\/a><\/p>\n<p><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> <a href=\"http:\/\/www.riminiduepuntozero.it\/per-la-soprintendenza-le-mura-bucate-non-sono-malatestiane\/\">http:\/\/www.riminiduepuntozero.it\/per-la-soprintendenza-le-mura-bucate-non-sono-malatestiane\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 di questi giorni la notizia dell\u2019avanzare del cantiere per la realizzazione del progetto che modificher\u00e0, in maniera drammatica, la vista del Ponte di Tiberio e delle mura lungo il corso del Marecchia a Rimini! Pi\u00f9 che il mero discorso [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[20,24,22],"tags":[36,5,12,14,122,15,123,8,7,10,121,124,4],"class_list":["post-492","post","type-post","status-publish","format-standard","hentry","category-architettura","category-restauro","category-urbanistica","tag-architetti","tag-architettura","tag-ettore-maria-mazzola","tag-ettore-mazzola","tag-la-spezia","tag-mazzola","tag-ponte-di-tiberio","tag-progettazione","tag-restauro","tag-rigenerazione-urbana","tag-rimini","tag-tutela-dei-beni-culturali","tag-urbanistica","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Rispetto per il Ponte di Tiberio a Rimini - virtutem forma decorat<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/07\/06\/rispetto-per-il-ponte-di-tiberio-a-rimini\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Rispetto per il Ponte di Tiberio a Rimini - virtutem forma decorat\" \/>\r\n<meta property=\"og:description\" content=\"\u00c8 di questi giorni la notizia dell\u2019avanzare del cantiere per la realizzazione del progetto che modificher\u00e0, in maniera drammatica, la vista del Ponte di Tiberio e delle mura lungo il corso del Marecchia a Rimini! Pi\u00f9 che il mero discorso [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/07\/06\/rispetto-per-il-ponte-di-tiberio-a-rimini\/\" \/>\r\n<meta property=\"og:site_name\" content=\"virtutem forma decorat\" \/>\r\n<meta property=\"article:published_time\" content=\"2017-07-06T14:03:45+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2017-07-09T11:14:59+00:00\" \/>\r\n<meta property=\"og:image\" content=\"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/comparto_4_-_z5_nmod.jpg\" \/>\r\n<meta name=\"author\" content=\"emmazzola\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@ettore_mazzola\" \/>\r\n<meta name=\"twitter:site\" content=\"@ettore_mazzola\" \/>\r\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"emmazzola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2017\\\/07\\\/06\\\/rispetto-per-il-ponte-di-tiberio-a-rimini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2017\\\/07\\\/06\\\/rispetto-per-il-ponte-di-tiberio-a-rimini\\\/\"},\"author\":{\"name\":\"emmazzola\",\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#\\\/schema\\\/person\\\/e29c0dd15f13008bd4c7682e6130977f\"},\"headline\":\"Rispetto per il Ponte di Tiberio a Rimini\",\"datePublished\":\"2017-07-06T14:03:45+00:00\",\"dateModified\":\"2017-07-09T11:14:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2017\\\/07\\\/06\\\/rispetto-per-il-ponte-di-tiberio-a-rimini\\\/\"},\"wordCount\":1677,\"commentCount\":2,\"publisher\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#\\\/schema\\\/person\\\/e29c0dd15f13008bd4c7682e6130977f\"},\"image\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2017\\\/07\\\/06\\\/rispetto-per-il-ponte-di-tiberio-a-rimini\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/comparto_4_-_z5_nmod.jpg\",\"keywords\":[\"architetti\",\"architettura\",\"ettore maria mazzola\",\"ettore mazzola\",\"La Spezia\",\"mazzola\",\"Ponte di Tiberio\",\"progettazione\",\"restauro\",\"rigenerazione urbana\",\"Rimini\",\"Tutela dei Beni Culturali\",\"Urbanistica\"],\"articleSection\":[\"Architettura\",\"restauro\",\"urbanistica\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2017\\\/07\\\/06\\\/rispetto-per-il-ponte-di-tiberio-a-rimini\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2017\\\/07\\\/06\\\/rispetto-per-il-ponte-di-tiberio-a-rimini\\\/\",\"url\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2017\\\/07\\\/06\\\/rispetto-per-il-ponte-di-tiberio-a-rimini\\\/\",\"name\":\"Rispetto per il Ponte di Tiberio a Rimini - virtutem forma decorat\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2017\\\/07\\\/06\\\/rispetto-per-il-ponte-di-tiberio-a-rimini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2017\\\/07\\\/06\\\/rispetto-per-il-ponte-di-tiberio-a-rimini\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/comparto_4_-_z5_nmod.jpg\",\"datePublished\":\"2017-07-06T14:03:45+00:00\",\"dateModified\":\"2017-07-09T11:14:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2017\\\/07\\\/06\\\/rispetto-per-il-ponte-di-tiberio-a-rimini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2017\\\/07\\\/06\\\/rispetto-per-il-ponte-di-tiberio-a-rimini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2017\\\/07\\\/06\\\/rispetto-per-il-ponte-di-tiberio-a-rimini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/comparto_4_-_z5_nmod.jpg\",\"contentUrl\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/comparto_4_-_z5_nmod.jpg\",\"width\":800,\"height\":500,\"caption\":\"Rendering del progetto in corso\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2017\\\/07\\\/06\\\/rispetto-per-il-ponte-di-tiberio-a-rimini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rispetto per il Ponte di Tiberio a Rimini\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#website\",\"url\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/\",\"name\":\"virtutem forma decorat\",\"description\":\"The new Architectural blog\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#\\\/schema\\\/person\\\/e29c0dd15f13008bd4c7682e6130977f\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#\\\/schema\\\/person\\\/e29c0dd15f13008bd4c7682e6130977f\",\"name\":\"emmazzola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/cropped-logoVirtutemFormaDecorat_Whigher.png\",\"url\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/cropped-logoVirtutemFormaDecorat_Whigher.png\",\"contentUrl\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/cropped-logoVirtutemFormaDecorat_Whigher.png\",\"width\":200,\"height\":79,\"caption\":\"emmazzola\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/cropped-logoVirtutemFormaDecorat_Whigher.png\"},\"url\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/author\\\/emmazzola\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rispetto per il Ponte di Tiberio a Rimini - virtutem forma decorat","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/07\/06\/rispetto-per-il-ponte-di-tiberio-a-rimini\/","og_locale":"it_IT","og_type":"article","og_title":"Rispetto per il Ponte di Tiberio a Rimini - virtutem forma decorat","og_description":"\u00c8 di questi giorni la notizia dell\u2019avanzare del cantiere per la realizzazione del progetto che modificher\u00e0, in maniera drammatica, la vista del Ponte di Tiberio e delle mura lungo il corso del Marecchia a Rimini! Pi\u00f9 che il mero discorso [&hellip;]","og_url":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/07\/06\/rispetto-per-il-ponte-di-tiberio-a-rimini\/","og_site_name":"virtutem forma decorat","article_published_time":"2017-07-06T14:03:45+00:00","article_modified_time":"2017-07-09T11:14:59+00:00","og_image":[{"url":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/comparto_4_-_z5_nmod.jpg","type":"","width":"","height":""}],"author":"emmazzola","twitter_card":"summary_large_image","twitter_creator":"@ettore_mazzola","twitter_site":"@ettore_mazzola","twitter_misc":{"Scritto da":"emmazzola","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/07\/06\/rispetto-per-il-ponte-di-tiberio-a-rimini\/#article","isPartOf":{"@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/07\/06\/rispetto-per-il-ponte-di-tiberio-a-rimini\/"},"author":{"name":"emmazzola","@id":"http:\/\/www.picweb.it\/emm\/blog\/#\/schema\/person\/e29c0dd15f13008bd4c7682e6130977f"},"headline":"Rispetto per il Ponte di Tiberio a Rimini","datePublished":"2017-07-06T14:03:45+00:00","dateModified":"2017-07-09T11:14:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/07\/06\/rispetto-per-il-ponte-di-tiberio-a-rimini\/"},"wordCount":1677,"commentCount":2,"publisher":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/#\/schema\/person\/e29c0dd15f13008bd4c7682e6130977f"},"image":{"@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/07\/06\/rispetto-per-il-ponte-di-tiberio-a-rimini\/#primaryimage"},"thumbnailUrl":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/comparto_4_-_z5_nmod.jpg","keywords":["architetti","architettura","ettore maria mazzola","ettore mazzola","La Spezia","mazzola","Ponte di Tiberio","progettazione","restauro","rigenerazione urbana","Rimini","Tutela dei Beni Culturali","Urbanistica"],"articleSection":["Architettura","restauro","urbanistica"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/07\/06\/rispetto-per-il-ponte-di-tiberio-a-rimini\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/07\/06\/rispetto-per-il-ponte-di-tiberio-a-rimini\/","url":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/07\/06\/rispetto-per-il-ponte-di-tiberio-a-rimini\/","name":"Rispetto per il Ponte di Tiberio a Rimini - virtutem forma decorat","isPartOf":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/07\/06\/rispetto-per-il-ponte-di-tiberio-a-rimini\/#primaryimage"},"image":{"@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/07\/06\/rispetto-per-il-ponte-di-tiberio-a-rimini\/#primaryimage"},"thumbnailUrl":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/comparto_4_-_z5_nmod.jpg","datePublished":"2017-07-06T14:03:45+00:00","dateModified":"2017-07-09T11:14:59+00:00","breadcrumb":{"@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/07\/06\/rispetto-per-il-ponte-di-tiberio-a-rimini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/07\/06\/rispetto-per-il-ponte-di-tiberio-a-rimini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/07\/06\/rispetto-per-il-ponte-di-tiberio-a-rimini\/#primaryimage","url":"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/comparto_4_-_z5_nmod.jpg","contentUrl":"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/07\/comparto_4_-_z5_nmod.jpg","width":800,"height":500,"caption":"Rendering del progetto in corso"},{"@type":"BreadcrumbList","@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/07\/06\/rispetto-per-il-ponte-di-tiberio-a-rimini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.picweb.it\/emm\/blog\/"},{"@type":"ListItem","position":2,"name":"Rispetto per il Ponte di Tiberio a Rimini"}]},{"@type":"WebSite","@id":"http:\/\/www.picweb.it\/emm\/blog\/#website","url":"http:\/\/www.picweb.it\/emm\/blog\/","name":"virtutem forma decorat","description":"The new Architectural blog","publisher":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/#\/schema\/person\/e29c0dd15f13008bd4c7682e6130977f"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.picweb.it\/emm\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"http:\/\/www.picweb.it\/emm\/blog\/#\/schema\/person\/e29c0dd15f13008bd4c7682e6130977f","name":"emmazzola","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/05\/cropped-logoVirtutemFormaDecorat_Whigher.png","url":"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/05\/cropped-logoVirtutemFormaDecorat_Whigher.png","contentUrl":"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/05\/cropped-logoVirtutemFormaDecorat_Whigher.png","width":200,"height":79,"caption":"emmazzola"},"logo":{"@id":"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/05\/cropped-logoVirtutemFormaDecorat_Whigher.png"},"url":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/author\/emmazzola\/"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8HWjS-7W","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/posts\/492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=492"}],"version-history":[{"count":1,"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/posts\/492\/revisions"}],"predecessor-version":[{"id":496,"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/posts\/492\/revisions\/496"}],"wp:attachment":[{"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}