{"id":479,"date":"2017-06-29T16:08:18","date_gmt":"2017-06-29T14:08:18","guid":{"rendered":"http:\/\/www.picweb.it\/emm\/blog\/?p=479"},"modified":"2017-06-29T17:29:58","modified_gmt":"2017-06-29T15:29:58","slug":"architettura-e-amore","status":"publish","type":"post","link":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/06\/29\/architettura-e-amore\/","title":{"rendered":"Architettura e Amore"},"content":{"rendered":"<p>Da quando, in nome di una visione distorta della modernit\u00e0, gli architetti hanno deciso di svincolarsi dalla tradizione, l\u2019architettura ha gradualmente perduto ogni senso morale.<\/p>\n<p>Nelle facolt\u00e0 di architettura, prima ancora di insegnare l\u2019arte di progettare edifici e citt\u00e0, bisognerebbe insegnare ai futuri architetti il principio dell\u2019etica della reciprocit\u00e0, o \u201cregola d\u2019oro\u201d: &#8220;<em>Non fare agli altri quello che non vorresti fosse fatto a te<\/em>&#8220;.<\/p>\n<p>Infatti, se mai questa regola venisse insegnata e appresa, nessuno mai si sognerebbe di usare gli esseri umani come cavie su cui sperimentare astrusi progetti, figli dell\u2019ideologia del momento, cosa che invece accade ormai ininterrottamente da almeno ottant\u2019anni.<\/p>\n<p>Nessuno, a meno di un marcato masochismo, progetterebbe per se stesso delle astruse ambientazioni spersonalizzanti \u2026 e infatti, come ebbe modo di denunciare oltre trent\u2019anni fa L\u00e9on Krier in un noto pezzo intitolato \u201c<em>Vizi Privati e Pubbliche Virt\u00f9<\/em>\u201d, pubblicato sulla rivista franco-belga \u201c<em>Archives d\u2019Architecture Moderne<\/em>\u201d, la totalit\u00e0 degli architetti che hanno progettato le peggiori mostruosit\u00e0 dell\u2019ultimo secolo, ama vivere e avere la propria attivit\u00e0 in splendidi e centralissimi edifici storici.<\/p>\n<p>Evidentemente, se quegli architetti non risiedono all\u2019interno delle mostruosit\u00e0 che concepiscono per gli altri, lo fanno perch\u00e9 \u201c<em>si vogliono bene<\/em>\u201d, si \u201c<em>amano<\/em>\u201d \u2026 mentre <em>odiano<\/em> il prossimo (masochista) che li ama!<\/p>\n<p>Il compianto grande architetto egiziano Hassan Fathy sosteneva: \u00ab<em>io dico che la bella Architettura \u00e8 un atto di civilt\u00e0 verso chi entra nell\u2019edificio; si inchina a voi ad ogni angolo, come in un minuetto \u2026 ogni costruzione brutta o insensata \u00e8 un insulto a chi le passa di fronte. Ogni edificio dovrebbe rappresentare un ornamento e un contributo alla propria cultura. Avendo deciso di abbandonare il passato, in quanto irrilevante, sono andati perduti o distrutti elementi di valore incalcolabile. La conoscenza rivelata del saggio \u00e8 ora sostituita dalla scienza analitica moderna, e la macchina ha rimpiazzato l\u2019abilit\u00e0 della mano artigiana<\/em>\u00bb<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>.<\/p>\n<p>Se nella frase di Fathy cambiassimo la parola \u201c<em>civilt\u00e0<\/em>\u201d con \u201c<em>amore<\/em>\u201d, otterremmo esattamente quello che ogni buona architettura dovrebbe comunicare: <em>la bella Architettura \u00e8 un atto di amore \u2026<\/em><\/p>\n<p>Quante volte, leggendo una guida ai luoghi dell\u2019arte, o ascoltando un documentario dedicato al nostro territorio, ci \u00e8 capitato di leggere e\/o ascoltare parole come \u201c<em>unione perfetta tra architettura e paesaggio<\/em>\u201d, \u201c<em>splendido connubio tra architettura e natura<\/em>\u201d, \u201c<em>un sodalizio perfetto tra l\u2019opera divina e quella umana<\/em>\u201d, ecc. \u2026<\/p>\n<p>Una unione tra due persone \u00e8 il frutto dell\u2019amore, un matrimonio che funziona si basa sulla capacit\u00e0 di rispettarsi reciprocamente, in un connubio, ci si completa vicendevolmente. Questo concetto, valido per gli esseri umani, pu\u00f2 estendersi certamente al \u201c<em>matrimonio<\/em>\u201d tra architettura e natura, dove la prevaricazione della prima sulla seconda farebbe venir meno le regole per una pacifica convivenza!<\/p>\n<p>Wolfang Goethe, nella suo \u201c<em>Viaggio in Italia<\/em>\u201d riportava una commovente descrizione del Teatro di Taormina, dicendo di trovarsi di fronte ad un panorama \u201c<em>dove l\u2019arte \u00e8 venuta in aiuto alla natura<\/em>\u201d.<\/p>\n<figure id=\"attachment_480\" aria-describedby=\"caption-attachment-480\" style=\"width: 2816px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"480\" data-permalink=\"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/06\/29\/architettura-e-amore\/cimg4249\/\" data-orig-file=\"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/06\/CIMG4249.jpg\" data-orig-size=\"2816,2112\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"CIMG4249\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;il Teatro di Taormina&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/06\/CIMG4249-1024x768.jpg\" class=\"size-full wp-image-480\" src=\"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/06\/CIMG4249.jpg\" alt=\"\" width=\"2816\" height=\"2112\" srcset=\"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/06\/CIMG4249.jpg 2816w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/06\/CIMG4249-300x225.jpg 300w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/06\/CIMG4249-768x576.jpg 768w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/06\/CIMG4249-1024x768.jpg 1024w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/06\/CIMG4249-700x525.jpg 700w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/06\/CIMG4249-520x390.jpg 520w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/06\/CIMG4249-360x270.jpg 360w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/06\/CIMG4249-250x188.jpg 250w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/06\/CIMG4249-100x75.jpg 100w\" sizes=\"(max-width: 2816px) 100vw, 2816px\" \/><figcaption id=\"caption-attachment-480\" class=\"wp-caption-text\">il Teatro di Taormina<\/figcaption><\/figure>\n<p>Purtroppo, dobbiamo ammettere con grande vergogna che sar\u00e0 molto difficile che un viaggiatore, tra diversi secoli, potr\u00e0 lasciarci descrizioni cos\u00ec struggenti dei paesaggi e delle architetture di oggi, sempre ammesso che sopravvivano al trascorrere del tempo.<\/p>\n<p>Un\u2019architettura concepita e realizzata con amore, trasmette amore e, come tale, suscita amore in chi la viva. Vivere in un luogo che trasmette amore, pace e tranquillit\u00e0 aiuta a vivere meglio.<\/p>\n<p>L\u2019amore, come anche l\u2019odio, \u00e8 un sentimento innato, che non necessita di essere spiegato agli individui. Se cresciamo nell\u2019amore saremo persone che difficilmente si avvicineranno al sentimento. Chi invece, per sua sfortuna, vien costretto a crescere nell\u2019odio e nel risentimento, necessiter\u00e0 di una educazione (riabilitazione) che gli consenta di abbandonare quel sentimento avvicinandosi all\u2019amore.<\/p>\n<p>Cos\u00ec come amore e odio non necessitano di spiegazioni per essere percepiti, anche il \u201c<em>bello<\/em>\u201d \u00e8 un qualcosa che viene percepito dagli esseri umani senza necessit\u00e0 di spiegazioni. Una cosa pu\u00f2 piacere o meno, n\u00e9 saranno sufficienti le parole di un <em>esperto<\/em> a far modificare l\u2019estetica di quel qualcosa.<\/p>\n<p>Oggi viviamo in una strana epoca, dove una pletora di parolai opera un vero e proprio lavaggio del cervello degli esseri umani, cercando di modificare il loro senso estetico. Qualcuno \u00e8 perfino arrivato a sostenere che, il motivo per cui la gente non comprende e non apprezza l\u2019architettura e l\u2019arte contemporanea, non vada ricercato nella loro incomprensibile estetica, ma nell\u2019ignoranza di chi non sia in grado di capire. Siamo cos\u00ec arrivati a stipendiare delle persone, al MAXXI di Roma, per poter \u201c<em>educare<\/em>\u201d la massa ignorante che non \u00e8 in grado di apprezzare la \u201c<em>bellezza<\/em>\u201d dell\u2019architettura moderna. Questa sorta di \u201c<em>terrorismo culturale<\/em>\u201d fa s\u00ec che molta gente \u2013 pur di evitare di venir considerata <em>ignorante<\/em> \u2013 decida di vestire i panni dell\u2019<em>intellettualoide radical-chic<\/em> il quale, non solo finge di apprezzare e comprendere ci\u00f2 che non abbia significato alcuno, ma addirittura critica \u2013 anche pesantemente \u2013 chi nella sua onest\u00e0 intellettuale continui a non comprendere!<\/p>\n<p>Tornando al pensiero di Goethe quindi, quando pensiamo all\u2019architettura dovremmo pensare ad un qualcosa che risulti un completamento della natura, non una violenza ad essa. Esistono ormai moltissimi studi che dimostrano quanto il tipo \u2013 e la forma \u2013 dell\u2019ambiente che ci circonda possa influenzare, in positivo o in negativo, la nostra salute fisica e mentale, ragion per cui, se vogliamo bene a noi stessi e al nostro prossimo, dovremmo mettere nella progettazione tutto l\u2019amore possibile.<\/p>\n<p>Personalmente, quando mi vien chiesto di sviluppare un progetto, nel rispetto delle richieste che mi vengono fatte, lo faccio come se lo stessi facendo per me stesso. Ancor prima di disegnare, cerco di immaginare quali sensazioni positive gradirei ricevere dagli ambienti che realizzer\u00f2. Allo stesso modo, quando i miei studenti mi chiedono delle indicazioni per concepire correttamente un progetto che dovranno sviluppare, piuttosto che metterli davanti ad un discorso ideologico, o piuttosto che chiedere loro di sfogliare qualche rivista patinata, suggerisco di fare un esercizio che richiede un piccolo sforzo mentale: \u201c<em>prima ancora di disegnare, provate a chiudere gli occhi immaginando di camminare all\u2019interno di quel progetto, cercate di immaginare quale possa essere la logica sequenza di spazi che si vorrebbero percorrere, quali le forme, i colori, le sensazioni di piacere visivo che si desidererebbe provare<\/em>\u201d.<\/p>\n<p>Se tutti progettassimo in questo modo, lo faremmo come se stessimo pensando al nostro benessere psicofisico, non di certo per farci del male!<\/p>\n<p>A tal proposito, anche se mi imbarazza un poco farlo, voglio ricordare un aneddoto della mia vita professionale che non dimenticher\u00f2 mai.<\/p>\n<p>Nella seconda met\u00e0 degli anni \u201990 venni contattato da una signora la quale, essendo rientrata in Italia dopo 35 anni vissuti in Germania, aveva necessit\u00e0 di ristrutturare un appartamento preso in affitto all\u2019ultimo piano di un moderno condominio di Trastevere \u2026 in realt\u00e0 si trattava degli ex locali lavatoio condominiali che un condomino aveva abusivamente accorpato, ampliato e trasformato in abitazione, condonandoli nel \u201894. L\u2019unica nota positiva era la potenziale vista dall\u2019ampia terrazza verso l\u2019Aventino!<\/p>\n<p>In occasione del primo incontro la cliente mi disse: \u201c<em>la prego architetto, non mi faccia cose strane e squadrate \u2026 torno in Italia dopo aver avuto a che fare con studenti di architettura e architetti tedeschi per 35 anni e non ne posso pi\u00f9 di queste cose, ho bisogno di ambienti normali, piacevoli e accoglienti che trasmettano amore per la vita<\/em>\u201d. Sorrisi per la sua franchezza e per il fatto che sembrava di sentir parlare me stesso, cos\u00ec la rassicurai ed elaborai il progetto cercando di soddisfare in toto le sue richieste, ritagliandole degli ambienti piacevoli e accoglienti che traessero il massimo vantaggio dalla vista. Un orribile localetto, precedentemente realizzato dal proprietario, venne modificato per realizzare una camera da letto (un vero e proprio <em>cubiculum<\/em> come la signora lo defin\u00ec) con il lato verso la terrazza caratterizzato da un finestrone ad arco rivolto verso l\u2019Aventino. Man mano che i lavori procedevano, ebbi modo di conoscere meglio la cliente e di chiederle come mai, se l\u2019immobile non fosse di sua propriet\u00e0, avesse deciso di investire tanto denaro per un appartamento che non le appartenesse.<\/p>\n<p>La risposta mi lasci\u00f2 di sasso! Mi disse di essere rientrata a Roma perch\u00e9, a causa di un male incurabile per il quale aveva gi\u00e0 subito un paio di interventi, le avevano dato pochi mesi di vita \u2026 sicch\u00e9 non ci sarebbe stato il tempo sufficiente per acquistare e ristrutturare una casa, n\u00e9 avrebbe avuto alcun senso farlo. Risultava pi\u00f9 logico fare questa operazione che le consentisse di non sprecare pi\u00f9 nemmeno un istante del poco tempo che le restava da vivere, s\u00ec da poter godere \u2013 quanto prima \u2013 del piacere trasmessogli dalla casa e dalla magnifica vista che aveva scelto per \u201c<em>andarsene in pace<\/em>\u201d!<\/p>\n<p>In quel lavoro ci misi tutto l\u2019amore che questa splendida persona meritava e, alla fine, lei ne fu contentissima. Circa un anno dopo la fine dei lavori, venni invitato con la mia famiglia a cena. Conoscendo la mia passione per il disegno e la pittura, al termine della cena mi regal\u00f2 una meravigliosa confezione di acquerelli presi in Germania, il regalo era accompagnato dal pi\u00f9 bel biglietto di ringraziamento che si possa sognare di ricevere. Un biglietto carico di amore e riconoscenza nei miei confronti, col quale mi comunicava che gli ultimi accertamenti dimostravano come il suo male fosse misteriosamente scomparso \u2026 lei per\u00f2 mi disse di essersi data una spiegazione dell\u2019accaduto, attribuendo la guarigione al nuovo e piacevole ambiente in cui viveva.<\/p>\n<p>A distanza di quasi vent\u2019anni, questa splendida persona \u00e8 ancora tra noi, si dedica al canto lirico e alla poesia e, con la sua storia, dimostra a tutti noi quanto la forza dell\u2019amore per le cose belle della vita possa aiutarci a superare tutto.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Hassan Fathy, <em>Construire avec le peuple<\/em>, Sindbad, Parigi, 1970<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da quando, in nome di una visione distorta della modernit\u00e0, gli architetti hanno deciso di svincolarsi dalla tradizione, l\u2019architettura ha gradualmente perduto ogni senso morale. Nelle facolt\u00e0 di architettura, prima ancora di insegnare l\u2019arte di progettare edifici e citt\u00e0, bisognerebbe [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[20,41],"tags":[5,18,13,111,12,14,15,8,11,17,16,4,19],"class_list":["post-479","post","type-post","status-publish","format-standard","hentry","category-architettura","category-progettazione-urbana","tag-architettura","tag-architettura-tradizionale","tag-archmazzola","tag-bellezza","tag-ettore-maria-mazzola","tag-ettore-mazzola","tag-mazzola","tag-progettazione","tag-progettazione-biofilica","tag-progettazione-tradizionale","tag-tradizione","tag-urbanistica","tag-urbanistica-tradizionale","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Architettura e Amore - virtutem forma decorat<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/06\/29\/architettura-e-amore\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Architettura e Amore - virtutem forma decorat\" \/>\r\n<meta property=\"og:description\" content=\"Da quando, in nome di una visione distorta della modernit\u00e0, gli architetti hanno deciso di svincolarsi dalla tradizione, l\u2019architettura ha gradualmente perduto ogni senso morale. Nelle facolt\u00e0 di architettura, prima ancora di insegnare l\u2019arte di progettare edifici e citt\u00e0, bisognerebbe [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/06\/29\/architettura-e-amore\/\" \/>\r\n<meta property=\"og:site_name\" content=\"virtutem forma decorat\" \/>\r\n<meta property=\"article:published_time\" content=\"2017-06-29T14:08:18+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2017-06-29T15:29:58+00:00\" \/>\r\n<meta property=\"og:image\" content=\"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/06\/CIMG4249.jpg\" \/>\r\n<meta name=\"author\" content=\"emmazzola\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@ettore_mazzola\" \/>\r\n<meta name=\"twitter:site\" content=\"@ettore_mazzola\" \/>\r\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"emmazzola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2017\\\/06\\\/29\\\/architettura-e-amore\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2017\\\/06\\\/29\\\/architettura-e-amore\\\/\"},\"author\":{\"name\":\"emmazzola\",\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#\\\/schema\\\/person\\\/e29c0dd15f13008bd4c7682e6130977f\"},\"headline\":\"Architettura e Amore\",\"datePublished\":\"2017-06-29T14:08:18+00:00\",\"dateModified\":\"2017-06-29T15:29:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2017\\\/06\\\/29\\\/architettura-e-amore\\\/\"},\"wordCount\":1615,\"commentCount\":9,\"publisher\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#\\\/schema\\\/person\\\/e29c0dd15f13008bd4c7682e6130977f\"},\"image\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2017\\\/06\\\/29\\\/architettura-e-amore\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/CIMG4249.jpg\",\"keywords\":[\"architettura\",\"architettura tradizionale\",\"archmazzola\",\"bellezza\",\"ettore maria mazzola\",\"ettore mazzola\",\"mazzola\",\"progettazione\",\"progettazione biofilica\",\"progettazione tradizionale\",\"tradizione\",\"Urbanistica\",\"urbanistica tradizionale\"],\"articleSection\":[\"Architettura\",\"progettazione urbana\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2017\\\/06\\\/29\\\/architettura-e-amore\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2017\\\/06\\\/29\\\/architettura-e-amore\\\/\",\"url\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2017\\\/06\\\/29\\\/architettura-e-amore\\\/\",\"name\":\"Architettura e Amore - virtutem forma decorat\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2017\\\/06\\\/29\\\/architettura-e-amore\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2017\\\/06\\\/29\\\/architettura-e-amore\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/CIMG4249.jpg\",\"datePublished\":\"2017-06-29T14:08:18+00:00\",\"dateModified\":\"2017-06-29T15:29:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2017\\\/06\\\/29\\\/architettura-e-amore\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2017\\\/06\\\/29\\\/architettura-e-amore\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2017\\\/06\\\/29\\\/architettura-e-amore\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/CIMG4249.jpg\",\"contentUrl\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/CIMG4249.jpg\",\"width\":2816,\"height\":2112,\"caption\":\"il Teatro di Taormina\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2017\\\/06\\\/29\\\/architettura-e-amore\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Architettura e Amore\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#website\",\"url\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/\",\"name\":\"virtutem forma decorat\",\"description\":\"The new Architectural blog\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#\\\/schema\\\/person\\\/e29c0dd15f13008bd4c7682e6130977f\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#\\\/schema\\\/person\\\/e29c0dd15f13008bd4c7682e6130977f\",\"name\":\"emmazzola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/cropped-logoVirtutemFormaDecorat_Whigher.png\",\"url\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/cropped-logoVirtutemFormaDecorat_Whigher.png\",\"contentUrl\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/cropped-logoVirtutemFormaDecorat_Whigher.png\",\"width\":200,\"height\":79,\"caption\":\"emmazzola\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/cropped-logoVirtutemFormaDecorat_Whigher.png\"},\"url\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/author\\\/emmazzola\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Architettura e Amore - virtutem forma decorat","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/06\/29\/architettura-e-amore\/","og_locale":"it_IT","og_type":"article","og_title":"Architettura e Amore - virtutem forma decorat","og_description":"Da quando, in nome di una visione distorta della modernit\u00e0, gli architetti hanno deciso di svincolarsi dalla tradizione, l\u2019architettura ha gradualmente perduto ogni senso morale. Nelle facolt\u00e0 di architettura, prima ancora di insegnare l\u2019arte di progettare edifici e citt\u00e0, bisognerebbe [&hellip;]","og_url":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/06\/29\/architettura-e-amore\/","og_site_name":"virtutem forma decorat","article_published_time":"2017-06-29T14:08:18+00:00","article_modified_time":"2017-06-29T15:29:58+00:00","og_image":[{"url":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/06\/CIMG4249.jpg","type":"","width":"","height":""}],"author":"emmazzola","twitter_card":"summary_large_image","twitter_creator":"@ettore_mazzola","twitter_site":"@ettore_mazzola","twitter_misc":{"Scritto da":"emmazzola","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/06\/29\/architettura-e-amore\/#article","isPartOf":{"@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/06\/29\/architettura-e-amore\/"},"author":{"name":"emmazzola","@id":"http:\/\/www.picweb.it\/emm\/blog\/#\/schema\/person\/e29c0dd15f13008bd4c7682e6130977f"},"headline":"Architettura e Amore","datePublished":"2017-06-29T14:08:18+00:00","dateModified":"2017-06-29T15:29:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/06\/29\/architettura-e-amore\/"},"wordCount":1615,"commentCount":9,"publisher":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/#\/schema\/person\/e29c0dd15f13008bd4c7682e6130977f"},"image":{"@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/06\/29\/architettura-e-amore\/#primaryimage"},"thumbnailUrl":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/06\/CIMG4249.jpg","keywords":["architettura","architettura tradizionale","archmazzola","bellezza","ettore maria mazzola","ettore mazzola","mazzola","progettazione","progettazione biofilica","progettazione tradizionale","tradizione","Urbanistica","urbanistica tradizionale"],"articleSection":["Architettura","progettazione urbana"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/06\/29\/architettura-e-amore\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/06\/29\/architettura-e-amore\/","url":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/06\/29\/architettura-e-amore\/","name":"Architettura e Amore - virtutem forma decorat","isPartOf":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/06\/29\/architettura-e-amore\/#primaryimage"},"image":{"@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/06\/29\/architettura-e-amore\/#primaryimage"},"thumbnailUrl":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/06\/CIMG4249.jpg","datePublished":"2017-06-29T14:08:18+00:00","dateModified":"2017-06-29T15:29:58+00:00","breadcrumb":{"@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/06\/29\/architettura-e-amore\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/06\/29\/architettura-e-amore\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/06\/29\/architettura-e-amore\/#primaryimage","url":"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/06\/CIMG4249.jpg","contentUrl":"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/06\/CIMG4249.jpg","width":2816,"height":2112,"caption":"il Teatro di Taormina"},{"@type":"BreadcrumbList","@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/06\/29\/architettura-e-amore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.picweb.it\/emm\/blog\/"},{"@type":"ListItem","position":2,"name":"Architettura e Amore"}]},{"@type":"WebSite","@id":"http:\/\/www.picweb.it\/emm\/blog\/#website","url":"http:\/\/www.picweb.it\/emm\/blog\/","name":"virtutem forma decorat","description":"The new Architectural blog","publisher":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/#\/schema\/person\/e29c0dd15f13008bd4c7682e6130977f"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.picweb.it\/emm\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"http:\/\/www.picweb.it\/emm\/blog\/#\/schema\/person\/e29c0dd15f13008bd4c7682e6130977f","name":"emmazzola","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/05\/cropped-logoVirtutemFormaDecorat_Whigher.png","url":"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/05\/cropped-logoVirtutemFormaDecorat_Whigher.png","contentUrl":"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/05\/cropped-logoVirtutemFormaDecorat_Whigher.png","width":200,"height":79,"caption":"emmazzola"},"logo":{"@id":"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/05\/cropped-logoVirtutemFormaDecorat_Whigher.png"},"url":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/author\/emmazzola\/"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8HWjS-7J","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/posts\/479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=479"}],"version-history":[{"count":1,"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/posts\/479\/revisions"}],"predecessor-version":[{"id":481,"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/posts\/479\/revisions\/481"}],"wp:attachment":[{"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}