{"id":1274,"date":"2018-06-16T13:27:43","date_gmt":"2018-06-16T11:27:43","guid":{"rendered":"http:\/\/www.picweb.it\/emm\/blog\/?p=1274"},"modified":"2018-06-16T17:10:08","modified_gmt":"2018-06-16T15:10:08","slug":"non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana","status":"publish","type":"post","link":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/06\/16\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\/","title":{"rendered":"Non solo Tor di Valle \u2026 riflessioni sul sistema tentacolare dell\u2019edilizia italiana"},"content":{"rendered":"<figure id=\"attachment_1275\" aria-describedby=\"caption-attachment-1275\" style=\"width: 635px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"1275\" data-permalink=\"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/06\/16\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\/manimani-354x500\/\" data-orig-file=\"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/06\/manimani-354x500.jpg\" data-orig-size=\"354,500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"manimani-354&amp;#215;500\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Manifesto del film \u2013 mai come oggi attuale \u2013 \u201cLe Mani sulla Citt\u00e0\u201d di Francesco Rosi&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/06\/manimani-354x500.jpg\" class=\" wp-image-1275\" src=\"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/06\/manimani-354x500.jpg\" alt=\"\" width=\"635\" height=\"897\" srcset=\"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/06\/manimani-354x500.jpg 354w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/06\/manimani-354x500-212x300.jpg 212w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/06\/manimani-354x500-250x353.jpg 250w, https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/06\/manimani-354x500-100x141.jpg 100w\" sizes=\"(max-width: 635px) 100vw, 635px\" \/><figcaption id=\"caption-attachment-1275\" class=\"wp-caption-text\">Manifesto del film \u2013 mai come oggi attuale \u2013 \u201cLe Mani sulla Citt\u00e0\u201d di Francesco Rosi<\/figcaption><\/figure>\n<p>All\u2019epoca in cui veniva abbattuto il Villino Naselli in via Ticino a Roma, il <em>Direttore della Soprintendenza Speciale Archeologica Belle Arti Paesaggio di Roma<\/em>, Francesco Prosperetti, nel rifiutarsi di rimettere in discussione la pratica, ebbe a dire: \u00ab<em>questione di gusto<\/em>\u00bb; a lui fece eco la <em>Direttrice Generale della Direzione Generale Arte e Architettura Contemporanee e Periferie Urbane<\/em> del MiBACT, Federica Galloni: \u201c<em>io sono favorevole al moderno<\/em>\u201d<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a> \u2026<\/p>\n<p>Eppure, documenti alla mano, avevamo in tutti i modi provato a scongiurare quello scempio<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a>, cercando di far comprendere al Prosperetti e alla Galloni che ci fosse pi\u00f9 di un motivo, storico e normativo, per dimostrare che quella follia non potesse compiersi, tuttavia il \u201c<em>gusto<\/em>\u201d \u2013 ergo l\u2019ideologia \u2013 ebbe il sopravvento sul rispetto delle regole.<\/p>\n<p>Oggi, alla luce di quello che sta venendo fuori da Tor di Valle, viene da chiedersi se fu davvero una questione di \u201c<em>gusto<\/em>\u201d e\/o di \u201c<em>ideologia<\/em>\u201d o se, anche in quel caso, vi furono pressioni esterne \u2026<\/p>\n<p>Purtroppo per\u00f2, nella bolgia mediatica di questi giorni \u2013 quasi esclusivamente incentrata sulla richiesta della testa della Raggi \u2013 per ovvie ragioni politiche, nessuno sembra volersi fare delle domande sulle infinite responsabilit\u00e0 della Regione (che a differenza della giunta Raggi annovera diversi indagati e l\u2019arresto dell\u2019ex assessore Civita del PD), n\u00e9 dei Ministri (Lotti, Calenda, Delrio, Franceschini e Madia) del precedente governo che, insieme ai dirigenti del CONI, hanno fatto pressioni ed elargito finanziamenti \u201c<em>alla velocit\u00e0 della luce<\/em>\u201d, affinch\u00e9 lo Stadio a Tor di Valle venisse realizzato.<\/p>\n<p>Accogliamo quindi con grande piacere l\u2019indagine a carico di Malag\u00f2, per\u00f2 attendiamo con ansia di vedere se diverr\u00e0 oggetto di indagini anche Luca Lotti, braccio destro di Matteo Renzi che, come ricorda \u201c<em>Il Fatto Quotidiano<\/em><a href=\"#_ftn3\" name=\"_ftnref3\">[3]<\/a>\u201d: <em>\u00abrisult\u00f2 determinante nell\u2019esito positivo della\u00a0<\/em><strong><em>conferenza dei servizi<\/em><\/strong><em>\u00a0<\/em><a href=\"https:\/\/www.ilfattoquotidiano.it\/2017\/11\/24\/stadio-della-roma-vicino-il-via-libera-definitivo-ma-con-i-soldi-del-governo-100-milioni-per-un-altro-ponte-sul-tevere\/4000344\/\"><em>quando nel novembre successivo arrivarono dal Governo rassicurazioni sul\u00a0<strong>finanziamento<\/strong>\u00a0pubblico per il<strong>\u00a0Ponte di Traiano<\/strong>.<\/em><\/a><em>\u00a0\u201cParnasi \u2013 si legge nell\u2019informativa \u2013 riferisce a\u00a0<\/em><strong><em>Mauro Baldissoni<\/em><\/strong><em>\u00a0(dg dell\u2019As Roma,\u00a0<\/em>nda<em>) che sta per incontrare Giovanni Malag\u00f2, affinch\u00e9 questi gli faccia conoscere tale Luca, che dal contesto della conversazione potrebbe identificarsi nel ministro dello sport Luca Lotti. Parnasi ribadisce che prima di Baldissoni, anche Malag\u00f2 si era reso disponibile a metterlo in relazione con \u2018Luca\u2019\u00bb.<\/em><\/p>\n<p>Sarebbe anche il caso di capire se gli ex ministri \u2013 quelli che in piena <em>spending review<\/em> di un Paese in ginocchio, trovarono in poche ore un finanziamento di 100 milioni per il Ponte<a href=\"#_ftn4\" name=\"_ftnref4\">[4]<\/a> della discordia, necessario a sbloccare la situazione di Tor di Valle \u2013 che nelle ultime ore si sono spinti ad accusare la Sindaca di Roma (non inquisita), piuttosto che pensare ai loro compagni di partito agli arresti e\/o indagati per la vicenda dello stadio<a href=\"#_ftn5\" name=\"_ftnref5\">[5]<\/a>, ci facciano sapere in base a quali logiche e sulla base di quali certezze di legittimit\u00e0 \u2013 del progetto e dell\u2019iter approvativo dello stadio \u2013 pensarono di poter elargire quella somma.<\/p>\n<p>Tuttavia, di tutte le ignobili vicende legate allo Stadio ce n\u2019\u00e8 una che, da molto tempo, urla vendetta, ed \u00e8 quella della inspiegabile (almeno fino a qualche giorno fa) rimozione dall\u2019incarico della Soprintendente Margherita Eichberg, rea di aver fatto il proprio dovere, istituendo il vincolo monumentale sull\u2019Ippodromo di Tor di Valle<a href=\"#_ftn6\" name=\"_ftnref6\">[6]<\/a>.<\/p>\n<p>L\u2019ex ministro Franceschini dovrebbe illuminarci su questa vicenda, che personalmente ritengo emblematica dell\u2019arroganza dei poteri forti.<\/p>\n<p>Per rinfrescare la memoria circa quello che si \u00e8 letto in questi ultimi giorni, \u201c<em>Il Fatto Quotidiano<\/em><a href=\"#_ftn7\" name=\"_ftnref7\">[7]<\/a>\u201d ci ha raccontato che: \u00ab<em>Per \u201cagganciare\u201d Prosperetti, Parnasi si rivolge all\u2019avvocato Claudio Santini \u2013 finito agli arresti domiciliari per aver incassato dal costruttore la somma di 53.440 euro \u2013 ex capo di gabinetto al Mibact durante il sottosegretariato del forzista Francesco Giro (fino al 2011). Santini lavora di concerto con uno dei dirigenti di Eurnova, Luca Caporilli, e con l\u2019architetto Paolo Desideri (non risulta indagato), socio e procuratore della ABDR Architetti Associati. Proprio la ABDR \u00e8 lo studio per il quale lavora Beatrice Morani, alias Beatrice Prosperetti, figlia del soprintendente (sul sito viene presentata col cognome della madre)<\/em>\u00bb.<\/p>\n<p>Mentre <em>Forzaroma.info<\/em> del 14 giugno u.s.<a href=\"#_ftn8\" name=\"_ftnref8\">[8]<\/a> ha riportato un breve estratto del dialogo tra l\u2019ex assessore regionale Civita e Parnasi, contenuto nelle intercettazioni citate nel provvedimento del Tribunale di Roma: \u00ab<em>Io ti voglio chiedere una cortesia per mio figlio? Tu me l\u2019avevi detto no \u2013 avrebbe detto l\u2019ex assessore \u2013 Allora ovviamente per ragioni\u00a0di opportunit\u00e0 nulla che riguarda le tue societ\u00e0. Ovviamente. Per\u00f2 tu mi avevi detto con qualcuno? Lui \u00e8 laureato in Economia. Se ti mando il curriculum?\u00bb. La conversazione con l\u2019imprenditore \u00e8 intercettata dagli inquirenti in un bar della Capitale. \u00abNo, non mandarmi il curriculum mandami la mail, il numero e la mail\u00bb gli avrebbe risposto Parnasi. \u00abAnche la cosa pi\u00f9 umile? All\u2019inizio? Pi\u00f9 \u00e8 umile all\u2019inizio e meglio \u00e8\u00bb avrebbe risposto Civita. \u00abNon ti preoccupare. Ci penso io\u00bb, lo avrebbe rassicurato Parnasi\u00bb.<\/em><\/p>\n<p>Daniele Autieri invece, su \u201c<em>La Repubblica<\/em>\u201d del 13 giugno<a href=\"#_ftn9\" name=\"_ftnref9\">[9]<\/a> u.s. scriveva: \u00ab<em>Dal grattacielo Bnl sulla stazione Tiburtina al quartiere Eurotower dell&#8217;Eur, dal palazzo che sarebbe dovuto diventare la nuova sede dell&#8217;Atac alle propriet\u00e0 di terreni e concessioni in giro per Roma, la lista dei business di Luca Parnasi, arrestato nell&#8217;ambito di un&#8217;inchiesta della procura di Roma che ruota intorno al progetto del nuovo stadio della Roma, va ben oltre l&#8217;impianto, divenuto &#8211; dopo la crisi finanziaria che ha messo in ginocchio le aziende del gruppo &#8211; l&#8217;ultima spiaggia in mano al rampollo, erede di una delle pi\u00f9 note e potenti famiglie di costruttori romani<\/em>\u00bb.<\/p>\n<p>In un mondo ideale, questo squallido intreccio tra palazzinari, archistars, soprintendenti e politici suggerirebbe di riprendere in mano tutte le realizzazioni degli ultimi decenni (incluso il modo in cui siano stati fatti il nuovo PRG, il Piano Casa e la nuova Legge Regionale sulla Rigenerazione Urbana), ma anche tutto il \u201c<em>piano di svendita del patrimonio immobiliare pubblico<\/em>\u201d, s\u00ec da comprendere quanto marciume si nasconda dietro il nuovo \u201c<em>sacco di Roma<\/em>\u201d \u2026 e invece tutto viene svilito da una perenne campagna elettorale, dove si preferisce attaccare i \u201cnemici politici\u201d, piuttosto che smascherare i burattinai e smantellare il sistema.<\/p>\n<p>In un mondo giusto inoltre, davanti a questo schifo generalizzato, la normativa sugli appalti, l\u2019esistenza delle \u201c<em>ditte di fiducia<\/em>\u201d e l\u2019affidamento degli incarichi ai \u201c<em>grandi studi<\/em>\u201d professionali verrebbero totalmente rivisti, dando spazio alle piccole e medie imprese \u201c<em>figlie di nessuno<\/em>\u201d e troppo spesso ridotte sul lastrico dalle \u201c<em>grandi aziende<\/em>\u201d grazie al sistema dei subappalti.<\/p>\n<p>A tal proposito sarebbe il caso che la Pubblica Amministrazione, piuttosto che appaltare a terzi, entrasse (o meglio rientrasse) in gioco, divenendo soggetto attivo nel processo edilizio, come avveniva all\u2019epoca della giunta Nathan, di Montemartini e di Orano<a href=\"#_ftn10\" name=\"_ftnref10\">[10]<\/a>, s\u00ec da fare da calmiere ad un sistema marcio e, come prevede il Codice di Procedura Civile, dare \u201c<em>l\u2019esempio del buon padre di famiglia<\/em><a href=\"#_ftn11\" name=\"_ftnref11\">[11]<\/a>\u201d.<\/p>\n<p>Infine, piuttosto che affidare gli incarichi ai cosiddetti \u201c<em>grandi studi<\/em>\u201d, spesso diretti da professionisti non in grado di tenere in mano una matita e che sfruttano i sempre disponibili giovani laureati, sarebbe ora di rivolgersi a tutti professionisti &#8220;<em>figli di nessuno<\/em>&#8221; che risultano costantemente tagliati fuori dalla competizione in nome di presunte norme \u201c<em>a garanzia della buona riuscita dell\u2019opera<\/em>\u201d che, nella realt\u00e0, mirano solo a rendere tutti schiavi della burocrazia in modo da favorire &#8220;<em>i soliti noti<\/em>&#8220;, indipendentemente dai ripetuti fallimenti estetici, economici e qualitativi!<\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> <a href=\"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/11\/18\/cio-che-non-fecero-ne-barbari-ne-barberini-lo-faranno-prosperetti-galloni-e-franceschini\/#_ftn8\">http:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/11\/18\/cio-che-non-fecero-ne-barbari-ne-barberini-lo-faranno-prosperetti-galloni-e-franceschini\/#_ftn8<\/a><\/p>\n<p><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> <a href=\"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/10\/16\/suggerimenti-preziosi-per-lannullamento-del-titolo-autorizzativo-di-via-ticino\/\">http:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/10\/16\/suggerimenti-preziosi-per-lannullamento-del-titolo-autorizzativo-di-via-ticino\/<\/a><\/p>\n<p><a href=\"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/10\/13\/novita-sul-progetto-di-via-ticino-3-a-firma-del-presidente-dellordine-degli-architetti-di-roma\/\">http:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/10\/13\/novita-sul-progetto-di-via-ticino-3-a-firma-del-presidente-dellordine-degli-architetti-di-roma\/<\/a><\/p>\n<p><a href=\"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/12\/31\/urbanistica-romana-e-sciacallaggio-politico-ora-basta\/\">http:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/12\/31\/urbanistica-romana-e-sciacallaggio-politico-ora-basta\/<\/a><\/p>\n<p><a href=\"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/10\/21\/dopo-via-ticino-incontri-ravvicinati-di-terzo-tipo-col-ministero-dei-beni-culturali\/\">http:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/10\/21\/dopo-via-ticino-incontri-ravvicinati-di-terzo-tipo-col-ministero-dei-beni-culturali\/<\/a><\/p>\n<p><a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a> <a href=\"https:\/\/www.ilfattoquotidiano.it\/2018\/06\/15\/stadio-roma-indagato-giovanni-malago-il-coni-da-lok-ai-parcheggi-poi-parnasi-offre-lavoro-al-compagno-della-figlia\/4428579\/\">https:\/\/www.ilfattoquotidiano.it\/2018\/06\/15\/stadio-roma-indagato-giovanni-malago-il-coni-da-lok-ai-parcheggi-poi-parnasi-offre-lavoro-al-compagno-della-figlia\/4428579\/<\/a><\/p>\n<p><a href=\"#_ftnref4\" name=\"_ftn4\">[4]<\/a> <a href=\"https:\/\/roma.zon.it\/stadio-della-roma-ponte\/\">https:\/\/roma.zon.it\/stadio-della-roma-ponte\/<\/a><\/p>\n<p><a href=\"#_ftnref5\" name=\"_ftn5\">[5]<\/a> <a href=\"https:\/\/www.democratica.com\/focus\/intervista-calenda-roma-virginia-raggi\/\">https:\/\/www.democratica.com\/focus\/intervista-calenda-roma-virginia-raggi\/<\/a><\/p>\n<p><a href=\"#_ftnref6\" name=\"_ftn6\">[6]<\/a> <a href=\"https:\/\/www.pagineromaniste.com\/lintervista-margherita-eichberg-vincolo-tor-valle-gia-messo-dal-comune\/\">https:\/\/www.pagineromaniste.com\/lintervista-margherita-eichberg-vincolo-tor-valle-gia-messo-dal-comune\/<\/a><\/p>\n<p><a href=\"#_ftnref7\" name=\"_ftn7\">[7]<\/a> <a href=\"https:\/\/www.ilfattoquotidiano.it\/2018\/06\/14\/stadio-roma-indagato-il-soprintendente-prosperetti-tolse-il-vincolo-sulle-tribune\/4427567\/\">https:\/\/www.ilfattoquotidiano.it\/2018\/06\/14\/stadio-roma-indagato-il-soprintendente-prosperetti-tolse-il-vincolo-sulle-tribune\/4427567\/<\/a><\/p>\n<p><a href=\"#_ftnref8\" name=\"_ftn8\">[8]<\/a> <a href=\"http:\/\/www.forzaroma.info\/rassegna-stampa\/il-messaggero\/il-dem-civita-e-il-lavoro-chiesto-per-il-figlio-e-laureato-ma-va-bene-un-ruolo-umile\/\">http:\/\/www.forzaroma.info\/rassegna-stampa\/il-messaggero\/il-dem-civita-e-il-lavoro-chiesto-per-il-figlio-e-laureato-ma-va-bene-un-ruolo-umile\/<\/a><\/p>\n<p><a href=\"#_ftnref9\" name=\"_ftn9\">[9]<\/a> <a href=\"http:\/\/roma.repubblica.it\/cronaca\/2018\/06\/13\/news\/parnasi_il_costruttore_figlio_d_arte_e_quell_azzardo_sullo_stadio_della_roma-198884366\/?ref=nrct-2\">http:\/\/roma.repubblica.it\/cronaca\/2018\/06\/13\/news\/parnasi_il_costruttore_figlio_d_arte_e_quell_azzardo_sullo_stadio_della_roma-198884366\/?ref=nrct-2<\/a><\/p>\n<p><a href=\"#_ftnref10\" name=\"_ftn10\">[10]<\/a> <a href=\"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/03\/31\/il-lavoro-nobilita-luomo-e-puo-anche-risolvere-i-conti-pubblici-una-lezione-dal-passato\/\">http:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/03\/31\/il-lavoro-nobilita-luomo-e-puo-anche-risolvere-i-conti-pubblici-una-lezione-dal-passato\/<\/a><\/p>\n<p><a href=\"#_ftnref11\" name=\"_ftn11\"><em><strong>[11]<\/strong><\/em><\/a> <em>Infatti, nel capitolo \u2013\u00a0<\/em><em>Obbligazioni del Mandatario<\/em><em>, art. 1710 (<\/em><em>Diligenza del mandatario<\/em><em>) si legge: \u00ab<\/em><em>Il mandatario \u00e8 tenuto a eseguire il mandato<\/em><em>\u00a0(2030, 2392, 2407, 2608)\u00a0<\/em><em>con la diligenza del buon padre di famiglia<\/em><em>\u00bb (1176 \u2013\u00a0<\/em><em>diligenza nell\u2019adempimento<\/em><em>).<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>All\u2019epoca in cui veniva abbattuto il Villino Naselli in via Ticino a Roma, il Direttore della Soprintendenza Speciale Archeologica Belle Arti Paesaggio di Roma, Francesco Prosperetti, nel rifiutarsi di rimettere in discussione la pratica, ebbe a dire: \u00abquestione di gusto\u00bb; [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[52,74,26,39,215,22],"tags":[36,5,13,164,12,15,50,32,49,4],"class_list":["post-1274","post","type-post","status-publish","format-standard","hentry","category-attualita","category-politica","category-professione","category-roma","category-stadio-as-roma-calcio","category-urbanistica","tag-architetti","tag-architettura","tag-archmazzola","tag-demolizione-in-via-ticino-a-roma","tag-ettore-maria-mazzola","tag-mazzola","tag-ministro-dei-beni-culturali","tag-roma","tag-stadio-della-as-roma","tag-urbanistica","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Non solo Tor di Valle \u2026 riflessioni sul sistema tentacolare dell\u2019edilizia italiana - virtutem forma decorat<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/06\/16\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Non solo Tor di Valle \u2026 riflessioni sul sistema tentacolare dell\u2019edilizia italiana - virtutem forma decorat\" \/>\r\n<meta property=\"og:description\" content=\"All\u2019epoca in cui veniva abbattuto il Villino Naselli in via Ticino a Roma, il Direttore della Soprintendenza Speciale Archeologica Belle Arti Paesaggio di Roma, Francesco Prosperetti, nel rifiutarsi di rimettere in discussione la pratica, ebbe a dire: \u00abquestione di gusto\u00bb; [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/06\/16\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\/\" \/>\r\n<meta property=\"og:site_name\" content=\"virtutem forma decorat\" \/>\r\n<meta property=\"article:published_time\" content=\"2018-06-16T11:27:43+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2018-06-16T15:10:08+00:00\" \/>\r\n<meta property=\"og:image\" content=\"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/06\/manimani-354x500.jpg\" \/>\r\n<meta name=\"author\" content=\"emmazzola\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@ettore_mazzola\" \/>\r\n<meta name=\"twitter:site\" content=\"@ettore_mazzola\" \/>\r\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"emmazzola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2018\\\/06\\\/16\\\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2018\\\/06\\\/16\\\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\\\/\"},\"author\":{\"name\":\"emmazzola\",\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#\\\/schema\\\/person\\\/e29c0dd15f13008bd4c7682e6130977f\"},\"headline\":\"Non solo Tor di Valle \u2026 riflessioni sul sistema tentacolare dell\u2019edilizia italiana\",\"datePublished\":\"2018-06-16T11:27:43+00:00\",\"dateModified\":\"2018-06-16T15:10:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2018\\\/06\\\/16\\\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\\\/\"},\"wordCount\":1367,\"commentCount\":4,\"publisher\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#\\\/schema\\\/person\\\/e29c0dd15f13008bd4c7682e6130977f\"},\"image\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2018\\\/06\\\/16\\\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/manimani-354x500.jpg\",\"keywords\":[\"architetti\",\"architettura\",\"archmazzola\",\"demolizione in Via Ticino a Roma\",\"ettore maria mazzola\",\"mazzola\",\"ministro dei beni culturali\",\"Roma\",\"Stadio della AS Roma\",\"Urbanistica\"],\"articleSection\":[\"attualit\u00e0\",\"politica\",\"professione\",\"Roma\",\"Stadio AS Roma Calcio\",\"urbanistica\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2018\\\/06\\\/16\\\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2018\\\/06\\\/16\\\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\\\/\",\"url\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2018\\\/06\\\/16\\\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\\\/\",\"name\":\"Non solo Tor di Valle \u2026 riflessioni sul sistema tentacolare dell\u2019edilizia italiana - virtutem forma decorat\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2018\\\/06\\\/16\\\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2018\\\/06\\\/16\\\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/manimani-354x500.jpg\",\"datePublished\":\"2018-06-16T11:27:43+00:00\",\"dateModified\":\"2018-06-16T15:10:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2018\\\/06\\\/16\\\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2018\\\/06\\\/16\\\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2018\\\/06\\\/16\\\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/manimani-354x500.jpg\",\"contentUrl\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/manimani-354x500.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2018\\\/06\\\/16\\\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Non solo Tor di Valle \u2026 riflessioni sul sistema tentacolare dell\u2019edilizia italiana\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#website\",\"url\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/\",\"name\":\"virtutem forma decorat\",\"description\":\"The new Architectural blog\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#\\\/schema\\\/person\\\/e29c0dd15f13008bd4c7682e6130977f\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#\\\/schema\\\/person\\\/e29c0dd15f13008bd4c7682e6130977f\",\"name\":\"emmazzola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/cropped-logoVirtutemFormaDecorat_Whigher.png\",\"url\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/cropped-logoVirtutemFormaDecorat_Whigher.png\",\"contentUrl\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/cropped-logoVirtutemFormaDecorat_Whigher.png\",\"width\":200,\"height\":79,\"caption\":\"emmazzola\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/cropped-logoVirtutemFormaDecorat_Whigher.png\"},\"url\":\"https:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/author\\\/emmazzola\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Non solo Tor di Valle \u2026 riflessioni sul sistema tentacolare dell\u2019edilizia italiana - virtutem forma decorat","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/06\/16\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\/","og_locale":"it_IT","og_type":"article","og_title":"Non solo Tor di Valle \u2026 riflessioni sul sistema tentacolare dell\u2019edilizia italiana - virtutem forma decorat","og_description":"All\u2019epoca in cui veniva abbattuto il Villino Naselli in via Ticino a Roma, il Direttore della Soprintendenza Speciale Archeologica Belle Arti Paesaggio di Roma, Francesco Prosperetti, nel rifiutarsi di rimettere in discussione la pratica, ebbe a dire: \u00abquestione di gusto\u00bb; [&hellip;]","og_url":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/06\/16\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\/","og_site_name":"virtutem forma decorat","article_published_time":"2018-06-16T11:27:43+00:00","article_modified_time":"2018-06-16T15:10:08+00:00","og_image":[{"url":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/06\/manimani-354x500.jpg","type":"","width":"","height":""}],"author":"emmazzola","twitter_card":"summary_large_image","twitter_creator":"@ettore_mazzola","twitter_site":"@ettore_mazzola","twitter_misc":{"Scritto da":"emmazzola","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/06\/16\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\/#article","isPartOf":{"@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/06\/16\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\/"},"author":{"name":"emmazzola","@id":"http:\/\/www.picweb.it\/emm\/blog\/#\/schema\/person\/e29c0dd15f13008bd4c7682e6130977f"},"headline":"Non solo Tor di Valle \u2026 riflessioni sul sistema tentacolare dell\u2019edilizia italiana","datePublished":"2018-06-16T11:27:43+00:00","dateModified":"2018-06-16T15:10:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/06\/16\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\/"},"wordCount":1367,"commentCount":4,"publisher":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/#\/schema\/person\/e29c0dd15f13008bd4c7682e6130977f"},"image":{"@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/06\/16\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\/#primaryimage"},"thumbnailUrl":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/06\/manimani-354x500.jpg","keywords":["architetti","architettura","archmazzola","demolizione in Via Ticino a Roma","ettore maria mazzola","mazzola","ministro dei beni culturali","Roma","Stadio della AS Roma","Urbanistica"],"articleSection":["attualit\u00e0","politica","professione","Roma","Stadio AS Roma Calcio","urbanistica"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/06\/16\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/06\/16\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\/","url":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/06\/16\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\/","name":"Non solo Tor di Valle \u2026 riflessioni sul sistema tentacolare dell\u2019edilizia italiana - virtutem forma decorat","isPartOf":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/06\/16\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\/#primaryimage"},"image":{"@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/06\/16\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\/#primaryimage"},"thumbnailUrl":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/06\/manimani-354x500.jpg","datePublished":"2018-06-16T11:27:43+00:00","dateModified":"2018-06-16T15:10:08+00:00","breadcrumb":{"@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/06\/16\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/06\/16\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/06\/16\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\/#primaryimage","url":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/06\/manimani-354x500.jpg","contentUrl":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/06\/manimani-354x500.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/06\/16\/non-solo-tor-di-valle-riflessioni-sul-sistema-tentacolare-delledilizia-italiana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.picweb.it\/emm\/blog\/"},{"@type":"ListItem","position":2,"name":"Non solo Tor di Valle \u2026 riflessioni sul sistema tentacolare dell\u2019edilizia italiana"}]},{"@type":"WebSite","@id":"http:\/\/www.picweb.it\/emm\/blog\/#website","url":"http:\/\/www.picweb.it\/emm\/blog\/","name":"virtutem forma decorat","description":"The new Architectural blog","publisher":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/#\/schema\/person\/e29c0dd15f13008bd4c7682e6130977f"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.picweb.it\/emm\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"http:\/\/www.picweb.it\/emm\/blog\/#\/schema\/person\/e29c0dd15f13008bd4c7682e6130977f","name":"emmazzola","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/05\/cropped-logoVirtutemFormaDecorat_Whigher.png","url":"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/05\/cropped-logoVirtutemFormaDecorat_Whigher.png","contentUrl":"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/05\/cropped-logoVirtutemFormaDecorat_Whigher.png","width":200,"height":79,"caption":"emmazzola"},"logo":{"@id":"https:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/05\/cropped-logoVirtutemFormaDecorat_Whigher.png"},"url":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/author\/emmazzola\/"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8HWjS-ky","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/posts\/1274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=1274"}],"version-history":[{"count":3,"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/posts\/1274\/revisions"}],"predecessor-version":[{"id":1278,"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/posts\/1274\/revisions\/1278"}],"wp:attachment":[{"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=1274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=1274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=1274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}