{"id":3196,"date":"2026-05-29T07:00:10","date_gmt":"2026-05-29T05:00:10","guid":{"rendered":"https:\/\/www.picweb.it\/blog\/?p=3196"},"modified":"2026-05-29T08:55:27","modified_gmt":"2026-05-29T06:55:27","slug":"te-o-caffe","status":"publish","type":"post","link":"https:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/","title":{"rendered":"T\u00e9 o caff\u00e8?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">1..S..al..D..(416)<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"858\" height=\"1024\" data-attachment-id=\"3197\" data-permalink=\"https:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/image_editor_output_image-261572139-17799607026793868055572169089799\/\" data-orig-file=\"https:\/\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/05\/image_editor_output_image-261572139-17799607026793868055572169089799.jpg\" data-orig-size=\"1675,2000\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"image_editor_output_image-261572139-17799607026793868055572169089799\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/05\/image_editor_output_image-261572139-17799607026793868055572169089799-858x1024.jpg\" src=\"https:\/\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/05\/image_editor_output_image-261572139-17799607026793868055572169089799-858x1024.jpg\" alt=\"\" class=\"wp-image-3197\" srcset=\"https:\/\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/05\/image_editor_output_image-261572139-17799607026793868055572169089799-858x1024.jpg 858w, https:\/\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/05\/image_editor_output_image-261572139-17799607026793868055572169089799-251x300.jpg 251w, https:\/\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/05\/image_editor_output_image-261572139-17799607026793868055572169089799-768x917.jpg 768w, https:\/\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/05\/image_editor_output_image-261572139-17799607026793868055572169089799-1286x1536.jpg 1286w, https:\/\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/05\/image_editor_output_image-261572139-17799607026793868055572169089799-1000x1194.jpg 1000w, https:\/\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/05\/image_editor_output_image-261572139-17799607026793868055572169089799-230x275.jpg 230w, https:\/\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/05\/image_editor_output_image-261572139-17799607026793868055572169089799-350x418.jpg 350w, https:\/\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/05\/image_editor_output_image-261572139-17799607026793868055572169089799-480x573.jpg 480w, https:\/\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/05\/image_editor_output_image-261572139-17799607026793868055572169089799.jpg 1675w\" sizes=\"(max-width: 858px) 100vw, 858px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>1..S..al..D..(416)<\/p>\n","protected":false},"author":1,"featured_media":3198,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[44],"tags":[213,559,224,225,46,221,196],"class_list":["post-3196","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sketches-schizzi","tag-1-s-al-d","tag-caffe","tag-draw","tag-drawing","tag-sketch","tag-sketchbook","tag-unosketchaldi"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"1..S..al..D..(416)\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Paolo Vecchio Ciprioti\"\/>\n\t<meta name=\"keywords\" content=\"1..s..al..d,caff\u00e8,draw,drawing,sketch,sketchbook,unosketchald\u00ec,sketches\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/2026\\\/05\\\/29\\\/te-o-caffe\\\/#article\",\"name\":\"T\\u00e9 o caff\\u00e8? | NimbusBlog\",\"headline\":\"T\\u00e9 o caff\\u00e8?\",\"author\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/author\\\/nimbuspicweb\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/image_editor_output_image-261572139-1779960717102.jpg\",\"width\":871,\"height\":932},\"datePublished\":\"2026-05-29T07:00:10+02:00\",\"dateModified\":\"2026-05-29T08:55:27+02:00\",\"inLanguage\":\"it-IT\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/2026\\\/05\\\/29\\\/te-o-caffe\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/2026\\\/05\\\/29\\\/te-o-caffe\\\/#webpage\"},\"articleSection\":\"Sketches, 1..S..al..D, caff\\u00e8, draw, drawing, sketch, sketchbook, unosketchald\\u00ec\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/2026\\\/05\\\/29\\\/te-o-caffe\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.picweb.it\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/category\\\/sketches-schizzi\\\/#listItem\",\"name\":\"Sketches\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/category\\\/sketches-schizzi\\\/#listItem\",\"position\":2,\"name\":\"Sketches\",\"item\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/category\\\/sketches-schizzi\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/2026\\\/05\\\/29\\\/te-o-caffe\\\/#listItem\",\"name\":\"T\\u00e9 o caff\\u00e8?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/2026\\\/05\\\/29\\\/te-o-caffe\\\/#listItem\",\"position\":3,\"name\":\"T\\u00e9 o caff\\u00e8?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/category\\\/sketches-schizzi\\\/#listItem\",\"name\":\"Sketches\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/#organization\",\"name\":\"NimbusBlog\",\"description\":\"The new Artblog\",\"url\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/author\\\/nimbuspicweb\\\/#author\",\"url\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/author\\\/nimbuspicweb\\\/\",\"name\":\"Paolo Vecchio Ciprioti\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/2026\\\/05\\\/29\\\/te-o-caffe\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b69000db6f56d1ccb84a6478fa67c32875aaeb2d34432c92d8f79e13a8e37392?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Paolo Vecchio Ciprioti\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/2026\\\/05\\\/29\\\/te-o-caffe\\\/#webpage\",\"url\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/2026\\\/05\\\/29\\\/te-o-caffe\\\/\",\"name\":\"T\\u00e9 o caff\\u00e8? | NimbusBlog\",\"description\":\"1..S..al..D..(416)\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/2026\\\/05\\\/29\\\/te-o-caffe\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/author\\\/nimbuspicweb\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/author\\\/nimbuspicweb\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/image_editor_output_image-261572139-1779960717102.jpg\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/2026\\\/05\\\/29\\\/te-o-caffe\\\/#mainImage\",\"width\":871,\"height\":932},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/2026\\\/05\\\/29\\\/te-o-caffe\\\/#mainImage\"},\"datePublished\":\"2026-05-29T07:00:10+02:00\",\"dateModified\":\"2026-05-29T08:55:27+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/\",\"name\":\"NimbusBlog\",\"description\":\"The new Artblog\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"T\u00e9 o caff\u00e8? | NimbusBlog","description":"1..S..al..D..(416)","canonical_url":"https:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/","robots":"max-image-preview:large","keywords":"1..s..al..d,caff\u00e8,draw,drawing,sketch,sketchbook,unosketchald\u00ec,sketches","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/#article","name":"T\u00e9 o caff\u00e8? | NimbusBlog","headline":"T\u00e9 o caff\u00e8?","author":{"@id":"https:\/\/www.picweb.it\/blog\/index.php\/author\/nimbuspicweb\/#author"},"publisher":{"@id":"https:\/\/www.picweb.it\/blog\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/05\/image_editor_output_image-261572139-1779960717102.jpg","width":871,"height":932},"datePublished":"2026-05-29T07:00:10+02:00","dateModified":"2026-05-29T08:55:27+02:00","inLanguage":"it-IT","mainEntityOfPage":{"@id":"https:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/#webpage"},"isPartOf":{"@id":"https:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/#webpage"},"articleSection":"Sketches, 1..S..al..D, caff\u00e8, draw, drawing, sketch, sketchbook, unosketchald\u00ec"},{"@type":"BreadcrumbList","@id":"https:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.picweb.it\/blog#listItem","position":1,"name":"Home","item":"https:\/\/www.picweb.it\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.picweb.it\/blog\/index.php\/category\/sketches-schizzi\/#listItem","name":"Sketches"}},{"@type":"ListItem","@id":"https:\/\/www.picweb.it\/blog\/index.php\/category\/sketches-schizzi\/#listItem","position":2,"name":"Sketches","item":"https:\/\/www.picweb.it\/blog\/index.php\/category\/sketches-schizzi\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/#listItem","name":"T\u00e9 o caff\u00e8?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.picweb.it\/blog#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/#listItem","position":3,"name":"T\u00e9 o caff\u00e8?","previousItem":{"@type":"ListItem","@id":"https:\/\/www.picweb.it\/blog\/index.php\/category\/sketches-schizzi\/#listItem","name":"Sketches"}}]},{"@type":"Organization","@id":"https:\/\/www.picweb.it\/blog\/#organization","name":"NimbusBlog","description":"The new Artblog","url":"https:\/\/www.picweb.it\/blog\/"},{"@type":"Person","@id":"https:\/\/www.picweb.it\/blog\/index.php\/author\/nimbuspicweb\/#author","url":"https:\/\/www.picweb.it\/blog\/index.php\/author\/nimbuspicweb\/","name":"Paolo Vecchio Ciprioti","image":{"@type":"ImageObject","@id":"https:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b69000db6f56d1ccb84a6478fa67c32875aaeb2d34432c92d8f79e13a8e37392?s=96&d=mm&r=g","width":96,"height":96,"caption":"Paolo Vecchio Ciprioti"}},{"@type":"WebPage","@id":"https:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/#webpage","url":"https:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/","name":"T\u00e9 o caff\u00e8? | NimbusBlog","description":"1..S..al..D..(416)","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/www.picweb.it\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/#breadcrumblist"},"author":{"@id":"https:\/\/www.picweb.it\/blog\/index.php\/author\/nimbuspicweb\/#author"},"creator":{"@id":"https:\/\/www.picweb.it\/blog\/index.php\/author\/nimbuspicweb\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/05\/image_editor_output_image-261572139-1779960717102.jpg","@id":"https:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/#mainImage","width":871,"height":932},"primaryImageOfPage":{"@id":"https:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/#mainImage"},"datePublished":"2026-05-29T07:00:10+02:00","dateModified":"2026-05-29T08:55:27+02:00"},{"@type":"WebSite","@id":"https:\/\/www.picweb.it\/blog\/#website","url":"https:\/\/www.picweb.it\/blog\/","name":"NimbusBlog","description":"The new Artblog","inLanguage":"it-IT","publisher":{"@id":"https:\/\/www.picweb.it\/blog\/#organization"}}]}},"aioseo_meta_data":{"post_id":"3196","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-05-29 05:36:28","updated":"2026-05-30 09:22:09","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.picweb.it\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.picweb.it\/blog\/index.php\/category\/sketches-schizzi\/\" title=\"Sketches\">Sketches<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tT\u00e9 o caff\u00e8?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.picweb.it\/blog"},{"label":"Sketches","link":"https:\/\/www.picweb.it\/blog\/index.php\/category\/sketches-schizzi\/"},{"label":"T\u00e9 o caff\u00e8?","link":"https:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>T\u00e9 o caff\u00e8? - NimbusBlog<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"http:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"T\u00e9 o caff\u00e8? - NimbusBlog\" \/>\r\n<meta property=\"og:description\" content=\"1..S..al..D..(416)\" \/>\r\n<meta property=\"og:url\" content=\"http:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/\" \/>\r\n<meta property=\"og:site_name\" content=\"NimbusBlog\" \/>\r\n<meta property=\"article:published_time\" content=\"2026-05-29T05:00:10+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2026-05-29T06:55:27+00:00\" \/>\r\n<meta property=\"og:image\" content=\"http:\/\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/05\/image_editor_output_image-261572139-1779960717102.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"871\" \/>\r\n\t<meta property=\"og:image:height\" content=\"932\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Paolo Vecchio Ciprioti\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@picweb2003\" \/>\r\n<meta name=\"twitter:site\" content=\"@picweb2003\" \/>\r\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paolo Vecchio Ciprioti\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/2026\\\/05\\\/29\\\/te-o-caffe\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/2026\\\/05\\\/29\\\/te-o-caffe\\\/\"},\"author\":{\"name\":\"Paolo Vecchio Ciprioti\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/#\\\/schema\\\/person\\\/f015660b7f332c11aa8f33829dd0af30\"},\"headline\":\"T\u00e9 o caff\u00e8?\",\"datePublished\":\"2026-05-29T05:00:10+00:00\",\"dateModified\":\"2026-05-29T06:55:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/2026\\\/05\\\/29\\\/te-o-caffe\\\/\"},\"wordCount\":6,\"publisher\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/#\\\/schema\\\/person\\\/f015660b7f332c11aa8f33829dd0af30\"},\"image\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/2026\\\/05\\\/29\\\/te-o-caffe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/image_editor_output_image-261572139-1779960717102.jpg\",\"keywords\":[\"1..S..al..D\",\"caff\u00e8\",\"draw\",\"drawing\",\"sketch\",\"sketchbook\",\"unosketchald\u00ec\"],\"articleSection\":[\"Sketches\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/2026\\\/05\\\/29\\\/te-o-caffe\\\/\",\"url\":\"http:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/2026\\\/05\\\/29\\\/te-o-caffe\\\/\",\"name\":\"T\u00e9 o caff\u00e8? - NimbusBlog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/2026\\\/05\\\/29\\\/te-o-caffe\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/2026\\\/05\\\/29\\\/te-o-caffe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/image_editor_output_image-261572139-1779960717102.jpg\",\"datePublished\":\"2026-05-29T05:00:10+00:00\",\"dateModified\":\"2026-05-29T06:55:27+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/2026\\\/05\\\/29\\\/te-o-caffe\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/2026\\\/05\\\/29\\\/te-o-caffe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/2026\\\/05\\\/29\\\/te-o-caffe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/image_editor_output_image-261572139-1779960717102.jpg\",\"contentUrl\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/image_editor_output_image-261572139-1779960717102.jpg\",\"width\":871,\"height\":932},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.picweb.it\\\/blog\\\/index.php\\\/2026\\\/05\\\/29\\\/te-o-caffe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00e9 o caff\u00e8?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/\",\"name\":\"NimbusBlog\",\"description\":\"The new Artblog\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/#\\\/schema\\\/person\\\/f015660b7f332c11aa8f33829dd0af30\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/#\\\/schema\\\/person\\\/f015660b7f332c11aa8f33829dd0af30\",\"name\":\"Paolo Vecchio Ciprioti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/wp-1744296708935.jpg\",\"url\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/wp-1744296708935.jpg\",\"contentUrl\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/wp-1744296708935.jpg\",\"width\":1058,\"height\":1058,\"caption\":\"Paolo Vecchio Ciprioti\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.picweb.it\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/wp-1744296708935.jpg\"},\"sameAs\":[\"http:\\\/\\\/www.picweb.it\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00e9 o caff\u00e8? - NimbusBlog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/","og_locale":"it_IT","og_type":"article","og_title":"T\u00e9 o caff\u00e8? - NimbusBlog","og_description":"1..S..al..D..(416)","og_url":"http:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/","og_site_name":"NimbusBlog","article_published_time":"2026-05-29T05:00:10+00:00","article_modified_time":"2026-05-29T06:55:27+00:00","og_image":[{"width":871,"height":932,"url":"http:\/\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/05\/image_editor_output_image-261572139-1779960717102.jpg","type":"image\/jpeg"}],"author":"Paolo Vecchio Ciprioti","twitter_card":"summary_large_image","twitter_creator":"@picweb2003","twitter_site":"@picweb2003","twitter_misc":{"Scritto da":"Paolo Vecchio Ciprioti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/#article","isPartOf":{"@id":"http:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/"},"author":{"name":"Paolo Vecchio Ciprioti","@id":"https:\/\/www.picweb.it\/blog\/#\/schema\/person\/f015660b7f332c11aa8f33829dd0af30"},"headline":"T\u00e9 o caff\u00e8?","datePublished":"2026-05-29T05:00:10+00:00","dateModified":"2026-05-29T06:55:27+00:00","mainEntityOfPage":{"@id":"http:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/"},"wordCount":6,"publisher":{"@id":"https:\/\/www.picweb.it\/blog\/#\/schema\/person\/f015660b7f332c11aa8f33829dd0af30"},"image":{"@id":"http:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/05\/image_editor_output_image-261572139-1779960717102.jpg","keywords":["1..S..al..D","caff\u00e8","draw","drawing","sketch","sketchbook","unosketchald\u00ec"],"articleSection":["Sketches"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/","url":"http:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/","name":"T\u00e9 o caff\u00e8? - NimbusBlog","isPartOf":{"@id":"https:\/\/www.picweb.it\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/#primaryimage"},"image":{"@id":"http:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/05\/image_editor_output_image-261572139-1779960717102.jpg","datePublished":"2026-05-29T05:00:10+00:00","dateModified":"2026-05-29T06:55:27+00:00","breadcrumb":{"@id":"http:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/#primaryimage","url":"https:\/\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/05\/image_editor_output_image-261572139-1779960717102.jpg","contentUrl":"https:\/\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/05\/image_editor_output_image-261572139-1779960717102.jpg","width":871,"height":932},{"@type":"BreadcrumbList","@id":"http:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/29\/te-o-caffe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.picweb.it\/blog\/"},{"@type":"ListItem","position":2,"name":"T\u00e9 o caff\u00e8?"}]},{"@type":"WebSite","@id":"https:\/\/www.picweb.it\/blog\/#website","url":"https:\/\/www.picweb.it\/blog\/","name":"NimbusBlog","description":"The new Artblog","publisher":{"@id":"https:\/\/www.picweb.it\/blog\/#\/schema\/person\/f015660b7f332c11aa8f33829dd0af30"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.picweb.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"https:\/\/www.picweb.it\/blog\/#\/schema\/person\/f015660b7f332c11aa8f33829dd0af30","name":"Paolo Vecchio Ciprioti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.picweb.it\/blog\/wp-content\/uploads\/2025\/04\/wp-1744296708935.jpg","url":"https:\/\/www.picweb.it\/blog\/wp-content\/uploads\/2025\/04\/wp-1744296708935.jpg","contentUrl":"https:\/\/www.picweb.it\/blog\/wp-content\/uploads\/2025\/04\/wp-1744296708935.jpg","width":1058,"height":1058,"caption":"Paolo Vecchio Ciprioti"},"logo":{"@id":"https:\/\/www.picweb.it\/blog\/wp-content\/uploads\/2025\/04\/wp-1744296708935.jpg"},"sameAs":["http:\/\/www.picweb.it"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/05\/image_editor_output_image-261572139-1779960717102.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8HYkB-Py","jetpack-related-posts":[{"id":1532,"url":"https:\/\/www.picweb.it\/blog\/index.php\/2025\/08\/01\/sketches\/","url_meta":{"origin":3196,"position":0},"title":"Sketches","author":"Paolo Vecchio Ciprioti","date":"1 Agosto 2025","format":false,"excerpt":"1..S..al..D..(115) ...sketches","rel":"","context":"In &quot;Sketches&quot;","block_context":{"text":"Sketches","link":"https:\/\/www.picweb.it\/blog\/index.php\/category\/sketches-schizzi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.picweb.it\/blog\/wp-content\/uploads\/2025\/07\/image_editor_output_image-1195396443-1753890047391.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2406,"url":"https:\/\/www.picweb.it\/blog\/index.php\/2026\/01\/10\/mans-sketch\/","url_meta":{"origin":3196,"position":1},"title":"Man&#8217;s sketch","author":"Paolo Vecchio Ciprioti","date":"10 Gennaio 2026","format":false,"excerpt":"1..S..al..D..(277)","rel":"","context":"In &quot;Sketches&quot;","block_context":{"text":"Sketches","link":"https:\/\/www.picweb.it\/blog\/index.php\/category\/sketches-schizzi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/01\/image_editor_output_image584989787-1767975552650.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/01\/image_editor_output_image584989787-1767975552650.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/01\/image_editor_output_image584989787-1767975552650.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/01\/image_editor_output_image584989787-1767975552650.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/01\/image_editor_output_image584989787-1767975552650.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":2163,"url":"https:\/\/www.picweb.it\/blog\/index.php\/2025\/12\/05\/nude-sketch\/","url_meta":{"origin":3196,"position":2},"title":"Nude sketch","author":"Paolo Vecchio Ciprioti","date":"5 Dicembre 2025","format":false,"excerpt":"1..S..al..D..(241)","rel":"","context":"In &quot;Sketches&quot;","block_context":{"text":"Sketches","link":"https:\/\/www.picweb.it\/blog\/index.php\/category\/sketches-schizzi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.picweb.it\/blog\/wp-content\/uploads\/2025\/11\/image_editor_output_image319478182-1764492497646.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.picweb.it\/blog\/wp-content\/uploads\/2025\/11\/image_editor_output_image319478182-1764492497646.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.picweb.it\/blog\/wp-content\/uploads\/2025\/11\/image_editor_output_image319478182-1764492497646.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":3133,"url":"https:\/\/www.picweb.it\/blog\/index.php\/2026\/05\/18\/sketch-of-a-man\/","url_meta":{"origin":3196,"position":3},"title":"Sketch of a man","author":"Paolo Vecchio Ciprioti","date":"18 Maggio 2026","format":false,"excerpt":"1..S..al..D..(405)","rel":"","context":"In &quot;Sketches&quot;","block_context":{"text":"Sketches","link":"https:\/\/www.picweb.it\/blog\/index.php\/category\/sketches-schizzi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.picweb.it\/blog\/wp-content\/uploads\/2026\/05\/image_editor_output_image1575123156-1779018601313.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1839,"url":"https:\/\/www.picweb.it\/blog\/index.php\/2025\/09\/29\/roma-2\/","url_meta":{"origin":3196,"position":4},"title":"Sketch di Roma","author":"Paolo Vecchio Ciprioti","date":"29 Settembre 2025","format":false,"excerpt":"1..S..al..D..(174)","rel":"","context":"In &quot;Sketches&quot;","block_context":{"text":"Sketches","link":"https:\/\/www.picweb.it\/blog\/index.php\/category\/sketches-schizzi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.picweb.it\/blog\/wp-content\/uploads\/2025\/09\/image_editor_output_image1113778077-1758968066948.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2094,"url":"https:\/\/www.picweb.it\/blog\/index.php\/2025\/11\/22\/still-life-sketch\/","url_meta":{"origin":3196,"position":5},"title":"Still life sketch","author":"Paolo Vecchio Ciprioti","date":"22 Novembre 2025","format":false,"excerpt":"1..S..al..D..(228)","rel":"","context":"In &quot;Sketches&quot;","block_context":{"text":"Sketches","link":"https:\/\/www.picweb.it\/blog\/index.php\/category\/sketches-schizzi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.picweb.it\/blog\/wp-content\/uploads\/2025\/11\/image_editor_output_image762205592-1763406085172.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.picweb.it\/blog\/wp-content\/uploads\/2025\/11\/image_editor_output_image762205592-1763406085172.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.picweb.it\/blog\/wp-content\/uploads\/2025\/11\/image_editor_output_image762205592-1763406085172.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.picweb.it\/blog\/wp-content\/uploads\/2025\/11\/image_editor_output_image762205592-1763406085172.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.picweb.it\/blog\/wp-content\/uploads\/2025\/11\/image_editor_output_image762205592-1763406085172.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.picweb.it\/blog\/index.php\/wp-json\/wp\/v2\/posts\/3196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.picweb.it\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.picweb.it\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.picweb.it\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.picweb.it\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=3196"}],"version-history":[{"count":1,"href":"https:\/\/www.picweb.it\/blog\/index.php\/wp-json\/wp\/v2\/posts\/3196\/revisions"}],"predecessor-version":[{"id":3199,"href":"https:\/\/www.picweb.it\/blog\/index.php\/wp-json\/wp\/v2\/posts\/3196\/revisions\/3199"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.picweb.it\/blog\/index.php\/wp-json\/wp\/v2\/media\/3198"}],"wp:attachment":[{"href":"https:\/\/www.picweb.it\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=3196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.picweb.it\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=3196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.picweb.it\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=3196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}