{"id":2232,"date":"2020-06-22T07:50:36","date_gmt":"2020-06-22T05:50:36","guid":{"rendered":"http:\/\/www.picweb.it\/emm\/blog\/?p=2232"},"modified":"2020-06-22T07:50:37","modified_gmt":"2020-06-22T05:50:37","slug":"gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte","status":"publish","type":"post","link":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2020\/06\/22\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\/","title":{"rendered":"Gli estremismi del politicamente corretto hanno ucciso anche l\u2019arte"},"content":{"rendered":"\n<p>Bramo il giorno in cui la nostra societ\u00e0 ipocrita si accorger\u00e0 che la sua idea di rispetto \u2013 solo di facciata \u2013 necessiti di essere rivista, in nome del reale senso del rispetto.<\/p>\n\n\n\n<p>Del resto, una societ\u00e0 la cui classe politica fa slogan \u201c<strong><em>rispettosi<\/em><\/strong>\u201d che inneggiano alla \u201c<strong><em>tolleranza<\/em><\/strong>\u201d, piuttosto che alla \u201c<strong><em>integrazione<\/em><\/strong><em>\u201d<\/em>, si commenta da s\u00e9.<\/p>\n\n\n\n<p>Chiss\u00e0 se certi buonisti, prima di azionare la lingua hanno mai provato ad assicurarsi che il cervello fosse bene inserito, chiss\u00e0 se costoro si sono mai resi conto che \u201c<strong><em>tollerare<\/em><\/strong>\u201d significhi \u201c<em>Resistere pazientemente a cose, persone o situazioni spiacevoli; accettare, sopportare; Sopportare condizioni o sostanze potenzialmente dannos<\/em>e\u201d.<\/p>\n\n\n\n<p>In pratica costoro non si sono mai resi conto che, con il loro inno alla tolleranza, non hanno fatto altro che confermare, ai razzisti di turno, che avessero ragione; in pratica, detto alla romana, essi hanno invitato tutti ad <strong><em>abbozzare<\/em><\/strong>: \u201c<em>dovete resistere pazientemente a queste persone o situazioni spiacevoli, dovete accettare, sopportare condizioni o situazioni potenzialmente dannose!<\/em>\u201d<\/p>\n\n\n\n<p>Allo stesso modo, questi idioti mascherati da politici, hanno deciso che fosse scorretto usare termini da sempre in uso nel nostro Paese, cos\u00ec quella che un tempo era la chiamata \u201c<em>cameriera<\/em>\u201d \u00e8 divenuta \u201c<em>collaboratrice domestica<\/em>\u201d, lo \u201c<em>spazzino<\/em>\u201d \u00e8 divenuto un \u201c<em>operatore ecologico<\/em>\u201d e cos\u00ec via, come se i nomi degli antichi mestieri equivalessero ad un\u2019offesa; come se cambiare il nome a qualcosa possa risultare sufficiente a cambiare la sostanza \u2026 ma ovviamente questa \u00e8 una sfumatura che difficilmente potrebbe venir compresa da parte di chi, avendo cambiato mille nomi ai patiti politici di appartenenza, creda di aver cambiato la sostanza del proprio immondo partito!<\/p>\n\n\n\n<p>Costoro, massacrando il nostro vocabolario, hanno perfino deciso che risultasse offensivo definire una donna \u201c<em>architetto<\/em>\u201d, \u201c<em>sindaco<\/em>\u201d ecc., invocando che si usassero termini come \u201c<em>architetta<\/em>\u201d, \u201c<em>sindaca<\/em>\u201d, ecc. \u2026 non meravigliamoci se qualche illuminato, tra i loro omologhi di sesso maschile chieder\u00e0 di usare termini come \u201c<em>dentisto<\/em>\u201d e \u201c<em>geometro<\/em>\u201d \u2026 nel frattempo il <em>pap\u00e0<\/em> e la <em>mamma<\/em> sono divenuti \u201c<em>genitore 1<\/em>\u201de\u201c<em>genitore 2<\/em>\u201d.<\/p>\n\n\n\n<p>Questa storia del \u201c<em>politicamente corretto<\/em>\u201d, della \u201c<em>parit\u00e0 di genere<\/em>\u201d, delle \u201c<em>quote rosa<\/em>\u201d ecc. nella \u201c<strong><em>societ\u00e0<\/em> <em>di facciata<\/em><\/strong>\u201d in cui viviamo sta portando ad una degenerazione completa che, in alcune realt\u00e0 straniere, ha portato ad imporre \u2013 perfino nelle istituzioni universitarie e nei centri di ricerca \u2013 la presenza di un ugual numero di rappresentanti delle \u201c<em>diverse categorie umane<\/em>\u201d \u2026 in pratica non \u00e8 pi\u00f9 il merito importante per poter svolgere un lavoro, ma l\u2019orientamento sessuale, la fede religiosa, il colore della pelle, ecc.<\/p>\n\n\n\n<p>L\u2019ipocrisia di questa societ\u00e0 di facciata sembra non avere pi\u00f9 limiti! Nel mio modesto cervello, incapace di vedere differenze, ho sempre pensato che il mondo, gli stati, ecc., potessero essere governati esclusivamente da donne, da omosessuali, da persone di colore, da persone di un unico credo religioso, ecc., purch\u00e9 dimostrassero di esserne all\u2019altezza \u2026 e non certamente da incapaci che stanno in nome di una <strong>finta immagine di uguaglianza<\/strong>!<\/p>\n\n\n\n<p>Eppure il mondo va come va e cos\u00ec e tutti, in nome del \u201c<em>politicamente corretto<\/em>\u201d, sono contenti \u2026 sebbene tutti sappiano di non esserlo affatto perch\u00e9, a denti stretti e nelle conversazioni private, la stragrande maggioranza degli esseri umani si lamenta di come vadano le cose, ma ha <strong>paura di esprimere il proprio parere<\/strong>. Siamo in democrazia (o almeno cos\u00ec ci raccontano), eppure sembra esser tornati all\u2019epoca dei manifesti \u201c<strong><em>taci, il nemico ascolta!<\/em><\/strong>\u201d.<\/p>\n\n\n\n<p>Io me ne frego e amo dire quello che penso, preferisco avere nemici piuttosto che finti amici, cos\u00ec colgo l\u2019occasione dell\u2019<strong><em>inno al cattivo gusto <\/em><\/strong>realizzato a Nantes per esprimere il mio disappunto sulla degenerazione in atto \u2026 sperando che con le accuse a me rivolte dagli ipocriti di turno non segua anche un risveglio collettivo delle coscienze.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"620\" height=\"340\" data-attachment-id=\"2233\" data-permalink=\"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2020\/06\/22\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\/donna-fessura\/\" data-orig-file=\"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2020\/06\/donna-fessura.jpg\" data-orig-size=\"620,340\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"donna-fessura\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;\u201cFontana\u201d della presunta artista Elsa Sahal, un&amp;#8217;opera che \u00e8 gi\u00e0 al centro di mille polemiche e che verr\u00e0 inaugurata l&amp;#8217;8 agosto a Nantes&lt;\/p&gt;\n\" data-large-file=\"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2020\/06\/donna-fessura.jpg\" src=\"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2020\/06\/donna-fessura.jpg\" alt=\"\" class=\"wp-image-2233\" srcset=\"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2020\/06\/donna-fessura.jpg 620w, http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2020\/06\/donna-fessura-300x165.jpg 300w, http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2020\/06\/donna-fessura-520x285.jpg 520w, http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2020\/06\/donna-fessura-360x197.jpg 360w, http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2020\/06\/donna-fessura-250x137.jpg 250w, http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2020\/06\/donna-fessura-100x55.jpg 100w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><figcaption>\u201cFontana\u201d della presunta artista Elsa Sahal, un&#8217;opera che \u00e8 gi\u00e0 al centro di mille polemiche e che verr\u00e0 inaugurata l&#8217;8 agosto a Nantes<\/figcaption><\/figure>\n\n\n\n<p>In questi giorni, mentre l\u2019ignorante furia iconoclasta sta distruggendo statue in giro per il mondo, la pseudo-artista Elsa Sahal \u2013 degna figlia dell\u2019attuale <em>sottocultura radical-chic<\/em> \u2013 ha realizzato una fontana chiamata, udite, udite, \u201c<em>Fontana<\/em>\u201d \u2026 l\u2019artista, evidentemente, ha giustamente pensato che, in una societ\u00e0 di imbecilli, qualcuno potesse pensare che il manufatto che getta acqua non lo fosse!<\/p>\n\n\n\n<p>L\u2019opera, orrenda e di pessimo gusto, che verr\u00e0 inaugurata l\u20198 agosto a Nantes riassume lo squallore della societ\u00e0 malata in cui viviamo e di cui ho detto in apertura &#8230; Non occorre sottolineare che questa vergogna accada in Francia, nazione principe della sottocultura in mano agli intellettualoidi radical-chic.<\/p>\n\n\n\n<p>L&#8217;artista \u00e8 convinta che quest&#8217;opera, rappresentando una <strong><em>donna che piscia in piedi<\/em><\/strong> serva a celebrare il &#8220;<strong><em>potere femminile<\/em><\/strong>&#8220;.<\/p>\n\n\n\n<p>In pratica, per questa donna \u2013 come nella peggior forma di maschilismo sessista \u2013 la donna \u00e8 una fessura, o se vogliamo un buco \u2026 peraltro con fattezze infantili che rasentano la pedofilia, tanto per aumentare la provocazione perversa.<\/p>\n\n\n\n<p>Che dire? Complimenti vivissimi a lei e ai suoi mecenati \u2026<\/p>\n\n\n\n<p>Quando, su Facebook, ho postato il link ad un articolo<a href=\"#_ftn1\">[1]<\/a> che raccontava di questo abominio, diverse donne, che probabilmente si erano limitate a guardare l\u2019immagine senza leggere l\u2019articolo, hanno commentato inveendo contro l\u2019autore, rigorosamente ritenuto un \u201c<em>uomo<\/em>\u201d, mentre altre, pi\u00f9 pacate, dopo averlo letto, hanno commentato dicendo che \u201c<em>una cosa del genere sembrerebbe ideata da un uomo<\/em>\u201d \u2026 per certe donne, evidentemente, la donna \u00e8 sempre innocente.<\/p>\n\n\n\n<p>Personalmente non penso affatto che una vergogna del genere possa scaturire esclusivamente da una mente maschile, perch\u00e9 gli uomini non sono tutti dei pervertiti, ergo sarebbe ora di farla finita anche con certi commenti &#8220;<em>sessisti<\/em>&#8221; contro il genere maschile!<\/p>\n\n\n\n<p>Semmai, sarebbe ora di riconoscere che determinate schifezze scaturiscano solo in menti perverse, indipendentemente dal proprio sesso, sebbene, sempre pi\u00f9 spesso, certe \u201c<em>produzioni artistiche<\/em>\u201d facciano capo a <strong>persone che vogliono sentirsi &#8220;<em>diverse<\/em>&#8221; e che, mai e poi mai, gradirebbero di sentirsi integrate, ergo &#8220;<em>uguali<\/em>&#8220;<\/strong> &#8230;<\/p>\n\n\n\n<p>Per certi \u201cartisti\u201d infatti, amanti degli eccessi e del tutto privi del senso del decoro, del pudore e del rispetto, \u00e8 molto pi\u00f9 facile evitare confronti e reclamare a gran voce il riconoscimento di una &#8220;<em>categoria a parte<\/em>&#8220;, che competere onestamente con tutta la societ\u00e0 che non avrebbe nulla in contrario alla loro partecipazione \u2026 dopo il crollo delle dittature, non ricordo di aver mai letto un bando che escludesse alcun genere umano.<\/p>\n\n\n\n<p>Mi riferisco a tutta quella marmaglia che ha chiesto ed ottenuto una finta &#8220;<em>parit\u00e0 di genere<\/em>&#8221; solo per arrivare ad imporre l&#8217;esistenza di un&#8217;arte, di un cinema, di un&#8217;architettura LGBT, per esempio. Questa immonda marmaglia \u2013 che non rappresenta affatto tutti gli omosessuali che ritengo persone rispettabilissime \u2013 grazie alla mania del &#8220;<em>politicamente corretto<\/em>&#8221; e della &#8220;<em>parit\u00e0 di genere<\/em>&#8220;, si \u00e8 infatti creata una vera e propria casta che, via via, ha preso potere nel mondo dell\u2019arte, tanto da arrivare ad imporre al mondo porcate inenarrabili il cui unico obiettivo \u00e8 quello di scioccare attraverso la provocazione e l&#8217;eccesso<a href=\"#_ftn2\">[2]<\/a>. Il senso del decoro \u00e8 morto!<\/p>\n\n\n\n<p>Sono queste le ragioni per cui mi auguro davvero che, chi decide le politiche del nostro Paese riesca a trovare il coraggio per fare un discorso, certamente impopolare, che ponga fine alla degenerazione che stiamo raggiungendo, grazie ad un concetto distorto di &#8220;<em>pari opportunit\u00e0<\/em>&#8220;.<\/p>\n\n\n\n<p>Costoro infatti, dovrebbero rendersi conto che occorra integrare le persone di diverso credo, colore, razza, orientamento sessuale, ecc., piuttosto che, per ragioni elettorali e\/o di falso rispetto, accontentare il capriccio di chi voglia, fortemente, sentirsi diverso, imponendo le proprie idee, spesso perverse, alla vista di tutti, bambini inclusi.<\/p>\n\n\n\n<p>Non si tratta di tirare in ballo idiozie bigotte, n\u00e9 altri fondamentalismi di qualsivoglia genere, ma semplicemente di riscoprire il comune senso del decoro e del rispetto di tutti, ricordandosi che <strong>la libert\u00e0 individuale deve, sempre, essere esercitata nel rispetto della libert\u00e0 altrui<\/strong>!<\/p>\n\n\n\n<p>Costoro necessitano di comprendere che<strong> la creazione \u2013 e differenziazione \u2013 di categorie sociali ad-hoc, non significa rispettare i rappresentanti di quelle categorie, ma semplicemente agevolare la ghettizzazione di chi voglia sentirsi diverso e non intenda assolutamente integrarsi, preferendo violentare gli altri con provocazioni figlie delle proprie eventuali perversioni<\/strong>.<\/p>\n\n\n\n<p>Un\u2019ultima annotazione storica \u00e8 necessaria<\/p>\n\n\n\n<p>Tornando al discorso sulla simbologia del \u201c<em>potere femminile<\/em>\u201d, vorrei ricordare che, per le civilt\u00e0 del passato, la potenza della donna si identificava nel culto della Magna Mater o Cibele, la divinit\u00e0 anatolica ambivalente, simbolo della forza creatrice e distruttrice della natura. Il potere femminile era anche identificato in altre divinit\u00e0 come Ishtar, Iside, Artemide, Astarte, Diana, Atena, Hera, Minerva, ecc. \u2026 e mai nessun artista, uomo o donna che fosse, ha osato rappresentare la donna o la divinit\u00e0 femminile riassumendola in una fessura.<\/p>\n\n\n\n<p>Esser passati dalla <strong>statuaria antica<\/strong> a delle \u201c<strong>gambe da Teletubbies con una pseudo-vagina<\/strong>\u201d \u00e8 segno che l\u2019arte \u00e8 stata assassinata dal \u201cpoliticamente corretto\u201d, mentre il senso del <strong>bello<\/strong> e quello del <strong>decoro<\/strong> sono morti e sepolti.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"681\" height=\"1024\" data-attachment-id=\"2234\" data-permalink=\"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2020\/06\/22\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\/cibele1\/\" data-orig-file=\"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2020\/06\/cibele1.jpg\" data-orig-size=\"768,1154\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"cibele1\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Cibele, arte romana, III secolo d.C., con dedica al senatore Virius Marcarianus, conservata al Museo archeologico nazionale di Napoli&lt;\/p&gt;\n\" data-large-file=\"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2020\/06\/cibele1-681x1024.jpg\" src=\"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2020\/06\/cibele1-681x1024.jpg\" alt=\"\" class=\"wp-image-2234\" srcset=\"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2020\/06\/cibele1-681x1024.jpg 681w, http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2020\/06\/cibele1-200x300.jpg 200w, http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2020\/06\/cibele1-700x1052.jpg 700w, http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2020\/06\/cibele1-520x781.jpg 520w, http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2020\/06\/cibele1-360x541.jpg 360w, http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2020\/06\/cibele1-250x376.jpg 250w, http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2020\/06\/cibele1-100x150.jpg 100w, http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2020\/06\/cibele1.jpg 768w\" sizes=\"(max-width: 681px) 100vw, 681px\" \/><figcaption>Cibele, arte romana, III secolo d.C., con dedica al senatore Virius Marcarianus, conservata al Museo archeologico nazionale di Napoli<\/figcaption><\/figure>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p><a href=\"#_ftnref1\">[1]<\/a> <a href=\"https:\/\/www.ilmessaggero.it\/mind_the_gap\/nantes_francia_bruxelles_pipi_statua_donne_maschilismo_mind_the_gap_elsa_sahal-5285766.html?fbclid=IwAR1vvCaRrmT07AfyQ439JqcDdCZUco32faBF2Nm9sgDpE6nOkOPF2Qysl1A\">https:\/\/www.ilmessaggero.it\/mind_the_gap\/nantes_francia_bruxelles_pipi_statua_donne_maschilismo_mind_the_gap_elsa_sahal-5285766.html?fbclid=IwAR1vvCaRrmT07AfyQ439JqcDdCZUco32faBF2Nm9sgDpE6nOkOPF2Qysl1A<\/a><\/p>\n\n\n\n<p><a href=\"#_ftnref2\">[2]<\/a> <a href=\"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/11\/23\/per-gli-intellettualoidi-radical-chic-e-tempo-di-vacche-grasse\/\">http:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/11\/23\/per-gli-intellettualoidi-radical-chic-e-tempo-di-vacche-grasse\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bramo il giorno in cui la nostra societ\u00e0 ipocrita si accorger\u00e0 che la sua idea di rispetto \u2013 solo di facciata \u2013 necessiti di essere rivista, in nome del reale senso del rispetto. Del resto, una societ\u00e0 la cui classe [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[45,295,52,296,281,74,58],"tags":[],"class_list":["post-2232","post","type-post","status-publish","format-standard","hentry","category-arte","category-arte-concettuale","category-attualita","category-bellezza","category-decoro-urbano","category-politica","category-societa","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Gli estremismi del politicamente corretto hanno ucciso anche l\u2019arte - virtutem forma decorat<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2020\/06\/22\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Gli estremismi del politicamente corretto hanno ucciso anche l\u2019arte - virtutem forma decorat\" \/>\r\n<meta property=\"og:description\" content=\"Bramo il giorno in cui la nostra societ\u00e0 ipocrita si accorger\u00e0 che la sua idea di rispetto \u2013 solo di facciata \u2013 necessiti di essere rivista, in nome del reale senso del rispetto. Del resto, una societ\u00e0 la cui classe [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2020\/06\/22\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\/\" \/>\r\n<meta property=\"og:site_name\" content=\"virtutem forma decorat\" \/>\r\n<meta property=\"article:published_time\" content=\"2020-06-22T05:50:36+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2020-06-22T05:50:37+00:00\" \/>\r\n<meta property=\"og:image\" content=\"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2020\/06\/donna-fessura.jpg\" \/>\r\n<meta name=\"author\" content=\"emmazzola\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@ettore_mazzola\" \/>\r\n<meta name=\"twitter:site\" content=\"@ettore_mazzola\" \/>\r\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"emmazzola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2020\\\/06\\\/22\\\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2020\\\/06\\\/22\\\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\\\/\"},\"author\":{\"name\":\"emmazzola\",\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#\\\/schema\\\/person\\\/e29c0dd15f13008bd4c7682e6130977f\"},\"headline\":\"Gli estremismi del politicamente corretto hanno ucciso anche l\u2019arte\",\"datePublished\":\"2020-06-22T05:50:36+00:00\",\"dateModified\":\"2020-06-22T05:50:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2020\\\/06\\\/22\\\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\\\/\"},\"wordCount\":1486,\"commentCount\":8,\"publisher\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#\\\/schema\\\/person\\\/e29c0dd15f13008bd4c7682e6130977f\"},\"image\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2020\\\/06\\\/22\\\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/donna-fessura.jpg\",\"articleSection\":[\"Arte\",\"arte concettuale\",\"attualit\u00e0\",\"bellezza\",\"Decoro urbano\",\"politica\",\"societ\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2020\\\/06\\\/22\\\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2020\\\/06\\\/22\\\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\\\/\",\"url\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2020\\\/06\\\/22\\\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\\\/\",\"name\":\"Gli estremismi del politicamente corretto hanno ucciso anche l\u2019arte - virtutem forma decorat\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2020\\\/06\\\/22\\\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2020\\\/06\\\/22\\\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/donna-fessura.jpg\",\"datePublished\":\"2020-06-22T05:50:36+00:00\",\"dateModified\":\"2020-06-22T05:50:37+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2020\\\/06\\\/22\\\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2020\\\/06\\\/22\\\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2020\\\/06\\\/22\\\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/donna-fessura.jpg\",\"contentUrl\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/donna-fessura.jpg\",\"width\":620,\"height\":340,\"caption\":\"\u201cFontana\u201d della presunta artista Elsa Sahal, un'opera che \u00e8 gi\u00e0 al centro di mille polemiche e che verr\u00e0 inaugurata l'8 agosto a Nantes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2020\\\/06\\\/22\\\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gli estremismi del politicamente corretto hanno ucciso anche l\u2019arte\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#website\",\"url\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/\",\"name\":\"virtutem forma decorat\",\"description\":\"The new Architectural blog\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#\\\/schema\\\/person\\\/e29c0dd15f13008bd4c7682e6130977f\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#\\\/schema\\\/person\\\/e29c0dd15f13008bd4c7682e6130977f\",\"name\":\"emmazzola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/cropped-logoVirtutemFormaDecorat_Whigher.png\",\"url\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/cropped-logoVirtutemFormaDecorat_Whigher.png\",\"contentUrl\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/cropped-logoVirtutemFormaDecorat_Whigher.png\",\"width\":200,\"height\":79,\"caption\":\"emmazzola\"},\"logo\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/cropped-logoVirtutemFormaDecorat_Whigher.png\"},\"url\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/author\\\/emmazzola\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gli estremismi del politicamente corretto hanno ucciso anche l\u2019arte - virtutem forma decorat","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2020\/06\/22\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\/","og_locale":"it_IT","og_type":"article","og_title":"Gli estremismi del politicamente corretto hanno ucciso anche l\u2019arte - virtutem forma decorat","og_description":"Bramo il giorno in cui la nostra societ\u00e0 ipocrita si accorger\u00e0 che la sua idea di rispetto \u2013 solo di facciata \u2013 necessiti di essere rivista, in nome del reale senso del rispetto. Del resto, una societ\u00e0 la cui classe [&hellip;]","og_url":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2020\/06\/22\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\/","og_site_name":"virtutem forma decorat","article_published_time":"2020-06-22T05:50:36+00:00","article_modified_time":"2020-06-22T05:50:37+00:00","og_image":[{"url":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2020\/06\/donna-fessura.jpg","type":"","width":"","height":""}],"author":"emmazzola","twitter_card":"summary_large_image","twitter_creator":"@ettore_mazzola","twitter_site":"@ettore_mazzola","twitter_misc":{"Scritto da":"emmazzola","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2020\/06\/22\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\/#article","isPartOf":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2020\/06\/22\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\/"},"author":{"name":"emmazzola","@id":"http:\/\/www.picweb.it\/emm\/blog\/#\/schema\/person\/e29c0dd15f13008bd4c7682e6130977f"},"headline":"Gli estremismi del politicamente corretto hanno ucciso anche l\u2019arte","datePublished":"2020-06-22T05:50:36+00:00","dateModified":"2020-06-22T05:50:37+00:00","mainEntityOfPage":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2020\/06\/22\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\/"},"wordCount":1486,"commentCount":8,"publisher":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/#\/schema\/person\/e29c0dd15f13008bd4c7682e6130977f"},"image":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2020\/06\/22\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\/#primaryimage"},"thumbnailUrl":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2020\/06\/donna-fessura.jpg","articleSection":["Arte","arte concettuale","attualit\u00e0","bellezza","Decoro urbano","politica","societ\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/www.picweb.it\/emm\/blog\/index.php\/2020\/06\/22\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2020\/06\/22\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\/","url":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2020\/06\/22\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\/","name":"Gli estremismi del politicamente corretto hanno ucciso anche l\u2019arte - virtutem forma decorat","isPartOf":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2020\/06\/22\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\/#primaryimage"},"image":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2020\/06\/22\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\/#primaryimage"},"thumbnailUrl":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2020\/06\/donna-fessura.jpg","datePublished":"2020-06-22T05:50:36+00:00","dateModified":"2020-06-22T05:50:37+00:00","breadcrumb":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2020\/06\/22\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.picweb.it\/emm\/blog\/index.php\/2020\/06\/22\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2020\/06\/22\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\/#primaryimage","url":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2020\/06\/donna-fessura.jpg","contentUrl":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2020\/06\/donna-fessura.jpg","width":620,"height":340,"caption":"\u201cFontana\u201d della presunta artista Elsa Sahal, un'opera che \u00e8 gi\u00e0 al centro di mille polemiche e che verr\u00e0 inaugurata l'8 agosto a Nantes"},{"@type":"BreadcrumbList","@id":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2020\/06\/22\/gli-estremismi-del-politicamente-corretto-hanno-ucciso-anche-larte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.picweb.it\/emm\/blog\/"},{"@type":"ListItem","position":2,"name":"Gli estremismi del politicamente corretto hanno ucciso anche l\u2019arte"}]},{"@type":"WebSite","@id":"http:\/\/www.picweb.it\/emm\/blog\/#website","url":"http:\/\/www.picweb.it\/emm\/blog\/","name":"virtutem forma decorat","description":"The new Architectural blog","publisher":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/#\/schema\/person\/e29c0dd15f13008bd4c7682e6130977f"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.picweb.it\/emm\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"http:\/\/www.picweb.it\/emm\/blog\/#\/schema\/person\/e29c0dd15f13008bd4c7682e6130977f","name":"emmazzola","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/05\/cropped-logoVirtutemFormaDecorat_Whigher.png","url":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/05\/cropped-logoVirtutemFormaDecorat_Whigher.png","contentUrl":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/05\/cropped-logoVirtutemFormaDecorat_Whigher.png","width":200,"height":79,"caption":"emmazzola"},"logo":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/05\/cropped-logoVirtutemFormaDecorat_Whigher.png"},"url":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/author\/emmazzola\/"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8HWjS-A0","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/posts\/2232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=2232"}],"version-history":[{"count":1,"href":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/posts\/2232\/revisions"}],"predecessor-version":[{"id":2235,"href":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/posts\/2232\/revisions\/2235"}],"wp:attachment":[{"href":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=2232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=2232"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=2232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}