{"id":1063,"date":"2018-02-08T09:58:55","date_gmt":"2018-02-08T08:58:55","guid":{"rendered":"http:\/\/www.picweb.it\/emm\/blog\/?p=1063"},"modified":"2018-02-08T15:03:22","modified_gmt":"2018-02-08T14:03:22","slug":"stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti","status":"publish","type":"post","link":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/02\/08\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\/","title":{"rendered":"Stadio a Tor di Valle \u2013 Ponzio Pilato e l\u2019incomprensibile silenzio degli innocenti"},"content":{"rendered":"<figure id=\"attachment_988\" aria-describedby=\"caption-attachment-988\" style=\"width: 967px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"988\" data-permalink=\"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/01\/12\/987\/sezioni\/\" data-orig-file=\"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/01\/sezioni.png\" data-orig-size=\"844,719\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"sezioni\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Planimetria dell\u2019ultimissima versione del MasterPlan dello Stadio indicante le linee di sezione (immagine fornita dall\u2019arch. Luciano Belli Laura e desunta dagli elaborati di progetto)&lt;\/p&gt;\n\" data-large-file=\"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/01\/sezioni.png\" class=\" wp-image-988\" src=\"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/01\/sezioni.png\" alt=\"\" width=\"967\" height=\"824\" srcset=\"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/01\/sezioni.png 844w, http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/01\/sezioni-300x256.png 300w, http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/01\/sezioni-768x654.png 768w, http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/01\/sezioni-700x596.png 700w, http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/01\/sezioni-520x443.png 520w, http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/01\/sezioni-360x307.png 360w, http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/01\/sezioni-250x213.png 250w, http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/01\/sezioni-100x85.png 100w\" sizes=\"(max-width: 967px) 100vw, 967px\" \/><figcaption id=\"caption-attachment-988\" class=\"wp-caption-text\">Planimetria dell\u2019ultimissima versione del MasterPlan dello Stadio indicante le linee di sezione (immagine fornita dall\u2019arch. Luciano Belli Laura e desunta dagli elaborati di progetto)<\/figcaption><\/figure>\n<p>Ad accentuare la posizione da Ponzio Pilato della Regione Lazio in materia di Stadio a Tor di Valle, registriamo la paradossale posizione dell\u2019assessore Michele Civita il quale, piuttosto che assumersi le responsabilit\u00e0 che cerca di scaricare altrove \u2013 probabilmente convinto dell\u2019ottusit\u00e0 del tifoso medio \u2013approfitta della situazione per promuovere una discutibile campagna elettorale \u2013 necessaria a dare continuit\u00e0 alla giunta regionale \u2013 concentrandosi sul bacino elettorale di fede romanista e lanciando proclami del tipo &#8220;<em>votate pe me che ve faccio fa\u2019 sto stadio<a href=\"#_ftn1\" name=\"_ftnref1\"><strong>[1]<\/strong><\/a><\/em>&#8220;.<\/p>\n<p>Ebbene, da romanista, ma soprattutto da cittadino di Roma, tengo a precisare che non solo non avr\u00e0 il mio voto, ma soprattutto che far\u00f2 di tutto, tramite la rete, affinch\u00e9 i cittadini romani e romanisti sappiano fino in fondo cosa significhi, economicamente, socialmente e in termini di ambiente e sicurezza<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a> realizzare quest\u2019immane follia targata PD.<\/p>\n<p>I romani non possono accettare che, con sotterfugi di ogni genere, possa realizzarsi un\u2019opera privata che preveda un investimento pubblico di circa 1mld di euro<a href=\"#_ftn3\" name=\"_ftnref3\">[3]<\/a> per renderla utilizzabile, senza che si debbano registrare decessi lungo le strade dirette verso il nuovo intervento, accentratore di traffico!<\/p>\n<p>Anche per questa ragione, pochi giorni fa avevo pubblicato un utilissimo testo scritto dell\u2019arch. Luciano Belli Laura<a href=\"#_ftn4\" name=\"_ftnref4\">[4]<\/a> che, forse pi\u00f9 di tutti, \u00e8 la persona che sta cercando di leggere tra le righe dei vari (discutibili) documenti prodotti per portare a compimento la porcata di Tor di Valle, evidenziando tutte le stranezze ed irregolarit\u00e0 procedimentali.<\/p>\n<p>Sebbene nel cappello introduttivo a quel testo avessi cercato di far riflettere tutti sul fatto che <em>il tempo stia inesorabilmente scorrendo<\/em>, ancora oggi non sembra esser stato fatto alcun passo, da parte di nessuno, verso l\u2019impugnazione dei documenti e il conseguente ricorso atto ad impedire che lo scempio si compia.<\/p>\n<p>Nel trasmettermi un nuovo testo, Luciano Belli Laura ha giustamente rimarcato l\u2019urgenza di comprendere che, <strong>se l&#8217;atto da impugnare al TAR \u00e8 la Determina G18433 datata 22 dicembre 2017, mancano veramente pochi giorni per il deposito del &#8220;ricorso&#8221; al TAR<\/strong> e, anche se ottimisticamente dovessimo ritenere che i 60 giorni decorrano dalla data di pubblicazione sul sito della Regione, ovvero il 9 gennaio 2018, mancherebbe comunque poco pi\u00f9 di un mese per valutare accuratamente tutta l\u2019immane documentazione e stendere un ricorso.<\/p>\n<p>Luciano Belli Laura fa altres\u00ec notare che, \u201c<em>oltre al rispetto della scadenza dei 60 giorni, occorre considerare che la notizia della formalizzazione del &#8220;ricorso&#8221; debba arrivare prima della pubblicazione \u2013 ai fini urbanistici contorti \u2013 del &#8220;progetto&#8221; all&#8217;Albo Pretorio del Campidoglio\u201d <\/em>solo cos\u00ec, infatti, \u201c<em>si potrebbe<\/em> <em>denunciare il subdolo tentativo di introdurre nel progetto quelle infrastrutture e quella verifica che, in conferenza di servizi regionale, non sono stati capaci di pretendere\u201d.<\/em><\/p>\n<p>Dopo aver letto il nuovo testo di Belli Laura riportato di seguito, e memore dello slogan elettorale dell\u2019attuale Giunta Capitolina mi sorge spontanea una domanda che rivolgo alla nostra sindaca: Considerata l\u2019evidenza dell\u2019abuso di potere operato dalla Regione, d\u2019accordo con i proponenti, che va ad esautorare il Consiglio Comunale dai suoi poteri, come \u00e8 possibile che l\u2019attuale giunta accetti di farsi mettere i piedi in testa, esponendosi a tutte le conseguenze del caso, consentendo la realizzazione di un\u2019opera che, sin da quando il M5S era all\u2019opposizione, era stata denunciata dall\u2019assessore Frongia<a href=\"#_ftn5\" name=\"_ftnref5\">[5]<\/a> in pi\u00f9 occasioni come una cosa inammissibile?<\/p>\n<p><strong>ATTI &amp; MISFATTI<\/strong><\/p>\n<p><strong>(Luciano Belli Laura)<\/strong><\/p>\n<p>Basta verificare le date dei documenti richiamati nell&#8217;articolo di Domenica 28 gennaio su \u201c<em>il Tempo<\/em>\u201d, per capire che l&#8217;averle tralasciate ha lasciato intendere che sia in atto un dissidio profondo, tra Roma Capitale, Citt\u00e0 Metropolitana e Regione Lazio, sul come procedere nell&#8217;iter autorizzativo del progetto del \u201c<em>Business Park con annesso Stadio a Tor di Valle<\/em>\u201d.<\/p>\n<p>Basta, invece, leggere la nota datata Gioved\u00ec 25 gennaio, per rendersi conto di come l&#8217;amministrazione procedente abbia alla fine deciso di risolvere le ultime resistenze delle amministrazioni partecipanti all&#8217;ultima Conferenza di Servizi decisoria: infatti, nel <a href=\"http:\/\/www.regione.lazio.it\/rl\/trasparenzastadio\/trasmissione-dati\/\">documento da pochissimo qui pubblicato<\/a>, s&#8217;evince che \u201c<strong><em>si prende atto<\/em><\/strong><em>\u201d di quanto chiarito dalle Amministrazioni\/Enti in merito a quanto riportato nella \u201cTabella di sintesi delle<strong> prescrizioni, osservazioni, raccomandazioni ed indicazioni <\/strong>contenute nei pareri<\/em>\u201d mentre, \u201c<strong><em>quanto elencato in tale tabella<\/em><\/strong>\u201d \u2013 considerata una mera sintesi \u2013 \u201c<strong><em>non sostituisce i singoli pareri delle Amministrazioni ed Enti intervenuti alla Conferenza<\/em><\/strong>\u201d, servendo quindi farvi esplicito rinvio \u201c<em>per l&#8217;integrale contenuto e motivazione delle prescrizioni medesime<\/em>\u201d.<\/p>\n<p><strong>In poche parole, la Regione comunica non ritenere necessario procedere ad integrare e\/o rettificare il provvedimento emesso il 22\/12\/2017, a chiusura della Conferenza di Servizi indetta il 15\/09\/2017.<\/strong><\/p>\n<p>Quanto esposto, quindi, lascia intendere che, tutto quanto espresso nota inviata il 12 gennaio in Regione, da Roma Capitale, risulti recepito e superato. In quella nota, occorre ricordarlo, si sostiene: \u201c<em>nel merito della richiesta dell\u2019inserimento nella variante urbanistica del Ponte, cos\u00ec come contenuta nella colonna prescrizioni, si fa presente che la stessa \u00e8 stata accolta esclusivamente come <strong>raccomandazione<\/strong> ma non pu\u00f2 essere oggetto della variante urbanistica come da verbale del 5 dicembre<\/em>\u201d.<\/p>\n<p>In fondo, come si suol dire, <em>il diavolo insegna a far le pentole ma non i coperchi<\/em>, ragion per cui appare assai poco informato chi cerchi di lasciare intendere che la comunicazione emessa dall&#8217;amministrazione Raggi fosse successiva alla nota dell&#8217;amministrazione Zingaretti \u2026 l\u2019assordante silenzio del Campidoglio, infatti, chiarisce bene chi abbia vinto la partita giocata in Conferenza di Servizi con la Pisana.<\/p>\n<p>Il tutto, nell&#8217;imminenza di una campagna elettorale, dove si tace su quanto fatto dall&#8217;amministrazione uscente al fine di riunirsi tutti in \u201c<em>Liberi e Uguali<\/em>\u201d per poterla riconfermare. Ebbene, in questa situazione, chi tacendo soccombe, non pu\u00f2 che ritenersi causa del suo stesso male \u2026 perfino venendo costretto dalla Regione a pubblicare all&#8217;Albo Pretorio del Comune l&#8217;intero progetto (ancora non adeguato per l\u2019ennesima volta dal Proponente privato), s\u00ec da consentire le osservazioni dei cittadini, sia sulla fantomatica \u201c<em>variante urbanistica<\/em>\u201d \u2013 raddoppiante la capacit\u00e0 insediativa permessa dal piano regolatore vigente \u2013 sia sulla chimerica \u201c<em>variante progettuale<\/em>\u201d, atta a reintrodurre infrastrutture necessarie, ma non pi\u00f9 finanziate \u2013 come dovuto \u2013 dal proponente, ovvero da quei ministri che, lanciando la palla in zona Cesarini, hanno rischiato l&#8217;autogol.<\/p>\n<p>Alla luce dei fatti, coloro i quali tacciono perch\u00e9 in tutt&#8217;altre faccende affaccendati, dovrebbero rendersi conto della necessit\u00e0 di dover urgentemente presentare un ricorso al TAR al fine di ottenere la sospensiva di questo assurdo atto amministrativo, che presume di poter chiudere in modo positivo una Conferenza di Servizi decisoria, emettendo un <strong><em>assenso con prescrizioni<\/em><\/strong> per un progetto di speculazione fondiaria ed immobiliare che, al di fuori dell&#8217;<em>Urbe<\/em>, verrebbe certamente rifiutato da chiunque non risulti obnubilato dal tifo calcistico o dalla fede partitica.<\/p>\n<p>Considerata la situazione, non si comprendono le ragioni del silenzio da parte dei comitati e delle associazioni che finora hanno operato in nome della legalit\u00e0 e trasparenza affinch\u00e9 questo scempio non si compia. Sembrerebbe quasi che tutti siano in attesa che piova dal cielo un cavillo legale non meglio identificato, che possa innescare il \u201cricorso\u201d sull\u2019atto amministrativo, a quel punto ritenuto impugnabile. N\u00e9 sembra che nessuno voglia accorgersi del fatto che gi\u00e0 tutto possa ritenersi impugnabile visto che, per assurdo, <strong>in Conferenza di Servizi s&#8217;\u00e8 presunto, <u>in maniera del tutto arbitraria<\/u>,\u00a0che un progetto assentito con innumerevoli prescrizioni possa costituire variante urbanistica!<\/strong><\/p>\n<p>Cos\u00ec come appare inequivocabile il fatto che la Determina G18433 del 22 dicembre 2017 risulti un documento <em>contra legem<\/em> \u2026 perfino contro le disposizioni del comma 2-bis dell&#8217;art. 62 del decreto 50, convertito in legge 95\/2017 (<em>leggina ad Pallottam<\/em>), giacch\u00e9 questa considera \u2013 sempre erroneamente \u2013che il &#8220;verbale&#8221; della Conferenza di Servizi possa costituire adozione di variante. Si rammenta infatti che, <u>un modulo procedimentale regionale valutante un &#8220;progetto&#8221;<\/u> (cio\u00e8 la CdS) <u>non pu\u00f2 adottare uno strumento urbanistico in variante a quello vigente, poich\u00e9 tale incombenza \u00e8 delegata esclusivamente al Consiglio Comunale<\/u>.<\/p>\n<p>Come non accorgersi <strong>l&#8217;adozione di una variante<\/strong> in Conferenza di Servizi equivalga ad un atto di\u00a0<strong>esautorazione<\/strong>, ovvero spodestamento (oggi a Roma e domani nel resto d\u2019Italia) <strong>del Consiglio Comunale<\/strong>?<\/p>\n<p>Del resto solo chi finga di non sapere pu\u00f2 ignorare il fatto che, a partire dalla Legge Ponte del 1967, il Consiglio Comunale <strong>risulta essere<em> \u201cl\u2019unico organo politico-amministrativo-elettivo-rappresentativo avente potere di deliberare ogni trasformazione territoriale, urbana, settoriale del suolo, attraverso adozione ecc. ecc. di &#8220;piani&#8221; a diverso livello, sia generali, sia esecutivi sia di loro varianti.<\/em><\/strong><\/p>\n<p>Alla luce di quanto esposto, dunque, non v\u2019\u00e8 alcuna ragione di continuare a tergiversare, poich\u00e9 risulta palese la legittimit\u00e0 di impugnare un atto amministrativo viziato da eccesso di potere \u2013 e\/o elusione di leggi \u2013 che si spinge ad <strong><em>INVITARE<\/em><\/strong> il Proponente privato \u2013 gi\u00e0 ricevente \u201c<em>tutta la documentazione relativa alla conclusione della Conferenza di Servizi, (consistente in: Pareri depositati alla Conferenza; Verbali delle sedute; Parere motivato VAS; Pronuncia di Valutazione di Impatto Ambientale; Determinazione conclusiva della CDS<\/em>\u201d) \u2013 a trasmettere il progetto definitivo \u201c<em>approvato in Conferenza e adeguato alle prescrizioni, osservazioni, raccomandazioni ed indicazioni richieste dagli Enti e contenute negli atti sopra citati a Roma Capitale, che provveder\u00e0 alla pubblicazione di apposito Avviso di Deposito in libera visione al pubblico<\/em>\u201d.<\/p>\n<p>Il tutto appare inoltre viziato da non poca <em>a<\/em>rroganza e protervia se, oltre all&#8217;invito, viene <strong><em>RAMMENTATO <\/em><\/strong>che \u201c<strong><em>solo ove il Progetto risulter\u00e0 esser stato adeguato alle prescrizioni ed alle ottemperanze indicate dalle Amministrazioni ed Enti nel corso della Conferenza di servizi, esso potr\u00e0 concludersi positivamente<\/em><\/strong>\u201d, vale a dire ai fini del <u>completamento<\/u> <u>dell&#8217;iter<\/u> <u>procedimentale<\/u> di cui alla L. 147\/2013 (la c. d. \u201cLegge Stadi\u201d) relativo all&#8217;intervento indicato in oggetto \u2026 ergo, ribadendo \u201c<strong><em>essere in corso presso questa Amministrazione<\/em><\/strong>\u201d un procedimento autorizzativo per il progetto di <em>Business Park con annesso Stadio<\/em>.<\/p>\n<p>Ecco quindi chiarirsi le ragioni per cui si faccia una campagna elettorale tesa a sottolineare l\u2019importanza di garantire una continuit\u00e0 amministrativa per chi, avendo il coltello dalla parte del manico, possa indurre il Campidoglio a pubblicare l&#8217;intero \u201cprogetto\u201d adeguato alle <em>prescrizioni<\/em> od <strong><em>ottemperanze<\/em><\/strong>, senza prendersi la briga di controllare, ancor prima dell&#8217;espletamento della procedura urbanistica, se Roma Capitale possa o meno aver tradotto le ipotetiche <em>raccomandazioni, <\/em>in osservanza di quanto viceversa imposto come obbligo.<\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> <a href=\"http:\/\/www.cinquequotidiano.it\/politica\/regione-lazio\/2018\/02\/01\/stadio-della-roma-civita-con-zingaretti-garantiamo-tempi-certi\/\">http:\/\/www.cinquequotidiano.it\/politica\/regione-lazio\/2018\/02\/01\/stadio-della-roma-civita-con-zingaretti-garantiamo-tempi-certi\/<\/a><\/p>\n<p><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> <a href=\"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/01\/08\/stadio-a-tor-di-valle-tutti-o-quasi-gli-abomini-della-determinazione-della-regione-lazio\/\">http:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/01\/08\/stadio-a-tor-di-valle-tutti-o-quasi-gli-abomini-della-determinazione-della-regione-lazio\/<\/a><\/p>\n<p><a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a> <a href=\"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/12\/08\/lo-stadio-a-tor-di-valle-si-fa-e-quasi-tutti-vissero-infelici-e-scontenti\/\">http:\/\/www.picweb.it\/emm\/blog\/index.php\/2017\/12\/08\/lo-stadio-a-tor-di-valle-si-fa-e-quasi-tutti-vissero-infelici-e-scontenti\/<\/a><\/p>\n<p><a href=\"#_ftnref4\" name=\"_ftn4\">[4]<\/a> <a href=\"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/02\/02\/stadio-della-roma-il-tempo-scorre-inesorabile\/\">http:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/02\/02\/stadio-della-roma-il-tempo-scorre-inesorabile\/<\/a><\/p>\n<p><a href=\"#_ftnref5\" name=\"_ftn5\">[5]<\/a> Per esempio <a href=\"https:\/\/www.youtube.com\/watch?v=HYBYEVYHIo4\">https:\/\/www.youtube.com\/watch?v=HYBYEVYHIo4<\/a> ; <a href=\"https:\/\/www.youtube.com\/watch?v=DMQQ8kHSFR8\">https:\/\/www.youtube.com\/watch?v=DMQQ8kHSFR8<\/a> ; ecc.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ad accentuare la posizione da Ponzio Pilato della Regione Lazio in materia di Stadio a Tor di Valle, registriamo la paradossale posizione dell\u2019assessore Michele Civita il quale, piuttosto che assumersi le responsabilit\u00e0 che cerca di scaricare altrove \u2013 probabilmente convinto [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[74,41,39,215,22],"tags":[13,12,14,177,15,32,49,4],"class_list":["post-1063","post","type-post","status-publish","format-standard","hentry","category-politica","category-progettazione-urbana","category-roma","category-stadio-as-roma-calcio","category-urbanistica","tag-archmazzola","tag-ettore-maria-mazzola","tag-ettore-mazzola","tag-luciano-belli-laura","tag-mazzola","tag-roma","tag-stadio-della-as-roma","tag-urbanistica","clearfix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Stadio a Tor di Valle \u2013 Ponzio Pilato e l\u2019incomprensibile silenzio degli innocenti - virtutem forma decorat<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/02\/08\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Stadio a Tor di Valle \u2013 Ponzio Pilato e l\u2019incomprensibile silenzio degli innocenti - virtutem forma decorat\" \/>\r\n<meta property=\"og:description\" content=\"Ad accentuare la posizione da Ponzio Pilato della Regione Lazio in materia di Stadio a Tor di Valle, registriamo la paradossale posizione dell\u2019assessore Michele Civita il quale, piuttosto che assumersi le responsabilit\u00e0 che cerca di scaricare altrove \u2013 probabilmente convinto [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/02\/08\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\/\" \/>\r\n<meta property=\"og:site_name\" content=\"virtutem forma decorat\" \/>\r\n<meta property=\"article:published_time\" content=\"2018-02-08T08:58:55+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2018-02-08T14:03:22+00:00\" \/>\r\n<meta property=\"og:image\" content=\"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/01\/sezioni.png\" \/>\r\n<meta name=\"author\" content=\"emmazzola\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@ettore_mazzola\" \/>\r\n<meta name=\"twitter:site\" content=\"@ettore_mazzola\" \/>\r\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"emmazzola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2018\\\/02\\\/08\\\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2018\\\/02\\\/08\\\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\\\/\"},\"author\":{\"name\":\"emmazzola\",\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#\\\/schema\\\/person\\\/e29c0dd15f13008bd4c7682e6130977f\"},\"headline\":\"Stadio a Tor di Valle \u2013 Ponzio Pilato e l\u2019incomprensibile silenzio degli innocenti\",\"datePublished\":\"2018-02-08T08:58:55+00:00\",\"dateModified\":\"2018-02-08T14:03:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2018\\\/02\\\/08\\\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\\\/\"},\"wordCount\":1717,\"commentCount\":1,\"publisher\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#\\\/schema\\\/person\\\/e29c0dd15f13008bd4c7682e6130977f\"},\"image\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2018\\\/02\\\/08\\\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/sezioni.png\",\"keywords\":[\"archmazzola\",\"ettore maria mazzola\",\"ettore mazzola\",\"Luciano Belli Laura\",\"mazzola\",\"Roma\",\"Stadio della AS Roma\",\"Urbanistica\"],\"articleSection\":[\"politica\",\"progettazione urbana\",\"Roma\",\"Stadio AS Roma Calcio\",\"urbanistica\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2018\\\/02\\\/08\\\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2018\\\/02\\\/08\\\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\\\/\",\"url\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2018\\\/02\\\/08\\\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\\\/\",\"name\":\"Stadio a Tor di Valle \u2013 Ponzio Pilato e l\u2019incomprensibile silenzio degli innocenti - virtutem forma decorat\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2018\\\/02\\\/08\\\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2018\\\/02\\\/08\\\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/sezioni.png\",\"datePublished\":\"2018-02-08T08:58:55+00:00\",\"dateModified\":\"2018-02-08T14:03:22+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2018\\\/02\\\/08\\\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2018\\\/02\\\/08\\\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2018\\\/02\\\/08\\\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/sezioni.png\",\"contentUrl\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/sezioni.png\",\"width\":844,\"height\":719,\"caption\":\"Planimetria dell\u2019ultimissima versione del MasterPlan dello Stadio indicante le linee di sezione (immagine fornita dall\u2019arch. Luciano Belli Laura e desunta dagli elaborati di progetto)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/2018\\\/02\\\/08\\\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stadio a Tor di Valle \u2013 Ponzio Pilato e l\u2019incomprensibile silenzio degli innocenti\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#website\",\"url\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/\",\"name\":\"virtutem forma decorat\",\"description\":\"The new Architectural blog\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#\\\/schema\\\/person\\\/e29c0dd15f13008bd4c7682e6130977f\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/#\\\/schema\\\/person\\\/e29c0dd15f13008bd4c7682e6130977f\",\"name\":\"emmazzola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/cropped-logoVirtutemFormaDecorat_Whigher.png\",\"url\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/cropped-logoVirtutemFormaDecorat_Whigher.png\",\"contentUrl\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/cropped-logoVirtutemFormaDecorat_Whigher.png\",\"width\":200,\"height\":79,\"caption\":\"emmazzola\"},\"logo\":{\"@id\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/cropped-logoVirtutemFormaDecorat_Whigher.png\"},\"url\":\"http:\\\/\\\/www.picweb.it\\\/emm\\\/blog\\\/index.php\\\/author\\\/emmazzola\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stadio a Tor di Valle \u2013 Ponzio Pilato e l\u2019incomprensibile silenzio degli innocenti - virtutem forma decorat","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/02\/08\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\/","og_locale":"it_IT","og_type":"article","og_title":"Stadio a Tor di Valle \u2013 Ponzio Pilato e l\u2019incomprensibile silenzio degli innocenti - virtutem forma decorat","og_description":"Ad accentuare la posizione da Ponzio Pilato della Regione Lazio in materia di Stadio a Tor di Valle, registriamo la paradossale posizione dell\u2019assessore Michele Civita il quale, piuttosto che assumersi le responsabilit\u00e0 che cerca di scaricare altrove \u2013 probabilmente convinto [&hellip;]","og_url":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/02\/08\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\/","og_site_name":"virtutem forma decorat","article_published_time":"2018-02-08T08:58:55+00:00","article_modified_time":"2018-02-08T14:03:22+00:00","og_image":[{"url":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/01\/sezioni.png","type":"","width":"","height":""}],"author":"emmazzola","twitter_card":"summary_large_image","twitter_creator":"@ettore_mazzola","twitter_site":"@ettore_mazzola","twitter_misc":{"Scritto da":"emmazzola","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/02\/08\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\/#article","isPartOf":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/02\/08\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\/"},"author":{"name":"emmazzola","@id":"http:\/\/www.picweb.it\/emm\/blog\/#\/schema\/person\/e29c0dd15f13008bd4c7682e6130977f"},"headline":"Stadio a Tor di Valle \u2013 Ponzio Pilato e l\u2019incomprensibile silenzio degli innocenti","datePublished":"2018-02-08T08:58:55+00:00","dateModified":"2018-02-08T14:03:22+00:00","mainEntityOfPage":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/02\/08\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\/"},"wordCount":1717,"commentCount":1,"publisher":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/#\/schema\/person\/e29c0dd15f13008bd4c7682e6130977f"},"image":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/02\/08\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\/#primaryimage"},"thumbnailUrl":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/01\/sezioni.png","keywords":["archmazzola","ettore maria mazzola","ettore mazzola","Luciano Belli Laura","mazzola","Roma","Stadio della AS Roma","Urbanistica"],"articleSection":["politica","progettazione urbana","Roma","Stadio AS Roma Calcio","urbanistica"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/02\/08\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/02\/08\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\/","url":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/02\/08\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\/","name":"Stadio a Tor di Valle \u2013 Ponzio Pilato e l\u2019incomprensibile silenzio degli innocenti - virtutem forma decorat","isPartOf":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/02\/08\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\/#primaryimage"},"image":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/02\/08\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\/#primaryimage"},"thumbnailUrl":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/01\/sezioni.png","datePublished":"2018-02-08T08:58:55+00:00","dateModified":"2018-02-08T14:03:22+00:00","breadcrumb":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/02\/08\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/02\/08\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/02\/08\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\/#primaryimage","url":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/01\/sezioni.png","contentUrl":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2018\/01\/sezioni.png","width":844,"height":719,"caption":"Planimetria dell\u2019ultimissima versione del MasterPlan dello Stadio indicante le linee di sezione (immagine fornita dall\u2019arch. Luciano Belli Laura e desunta dagli elaborati di progetto)"},{"@type":"BreadcrumbList","@id":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/2018\/02\/08\/stadio-a-tor-di-valle-ponzio-pilato-e-lincomprensibile-silenzio-degli-innocenti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.picweb.it\/emm\/blog\/"},{"@type":"ListItem","position":2,"name":"Stadio a Tor di Valle \u2013 Ponzio Pilato e l\u2019incomprensibile silenzio degli innocenti"}]},{"@type":"WebSite","@id":"http:\/\/www.picweb.it\/emm\/blog\/#website","url":"http:\/\/www.picweb.it\/emm\/blog\/","name":"virtutem forma decorat","description":"The new Architectural blog","publisher":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/#\/schema\/person\/e29c0dd15f13008bd4c7682e6130977f"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.picweb.it\/emm\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"http:\/\/www.picweb.it\/emm\/blog\/#\/schema\/person\/e29c0dd15f13008bd4c7682e6130977f","name":"emmazzola","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/05\/cropped-logoVirtutemFormaDecorat_Whigher.png","url":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/05\/cropped-logoVirtutemFormaDecorat_Whigher.png","contentUrl":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/05\/cropped-logoVirtutemFormaDecorat_Whigher.png","width":200,"height":79,"caption":"emmazzola"},"logo":{"@id":"http:\/\/www.picweb.it\/emm\/blog\/wp-content\/uploads\/2017\/05\/cropped-logoVirtutemFormaDecorat_Whigher.png"},"url":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/author\/emmazzola\/"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8HWjS-h9","jetpack-related-posts":[],"jetpack_likes_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/posts\/1063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=1063"}],"version-history":[{"count":2,"href":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/posts\/1063\/revisions"}],"predecessor-version":[{"id":1066,"href":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/posts\/1063\/revisions\/1066"}],"wp:attachment":[{"href":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=1063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=1063"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.picweb.it\/emm\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=1063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}